{"id":6012,"date":"2025-01-16T13:38:59","date_gmt":"2025-01-16T05:38:59","guid":{"rendered":"https:\/\/www.gradinlifts.com\/?post_type=product&#038;p=6012"},"modified":"2025-01-16T14:47:17","modified_gmt":"2025-01-16T06:47:17","slug":"g-v11-electric-articulating-boom-lifts","status":"publish","type":"product","link":"https:\/\/www.gradinlifts.com\/ko\/product\/g-v11-electric-articulating-boom-lifts\/","title":{"rendered":"11m \uc804\ub3d9 \uad74\uc808\uc2dd \ubd90 \ub9ac\ud504\ud2b8"},"content":{"rendered":"<style>.kb-row-layout-id6012_8ffc81-6e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6012_8ffc81-6e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6012_8ffc81-6e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6012_8ffc81-6e{background-color:#ebeef2;}.kb-row-layout-id6012_8ffc81-6e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6012_8ffc81-6e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6012_8ffc81-6e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6012_8ffc81-6e alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column6012_fa158c-22 > .kt-inside-inner-col{padding-right:12rem;padding-bottom:3rem;padding-left:12rem;}.kadence-column6012_fa158c-22 > .kt-inside-inner-col,.kadence-column6012_fa158c-22 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_fa158c-22 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_fa158c-22 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_fa158c-22 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_fa158c-22 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_fa158c-22{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_fa158c-22 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_fa158c-22 > .kt-inside-inner-col{padding-right:0rem;padding-bottom:2rem;padding-left:0rem;flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_fa158c-22\"><div class=\"kt-inside-inner-col\"><style>.kt-tabs-id6012_fd5905-97 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:1px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid var(u002du002dglobal-palette7, #eeeeee);border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:0px;background:#ebeef2;}.wp-block-kadence-tabs .kt-tabs-id6012_fd5905-97 > .kt-tabs-title-list li{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id6012_fd5905-97 > .kt-tabs-title-list li:last-child{margin-right:0px;}.wp-block-kadence-tabs .kt-tabs-id6012_fd5905-97 > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id6012_fd5905-97 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{line-height:1.4em;font-weight:regular;font-style:normal;border-top-width:0px;border-right-width:0px;border-bottom-width:4px;border-left-width:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:1rem;padding-right:2rem;padding-bottom:1rem;padding-left:2rem;border-color:var(u002du002dglobal-palette9, #ffffff);color:var(u002du002dglobal-palette5, #444444);background:var(u002du002dglobal-palette9, #ffffff);}.wp-block-kadence-tabs .kt-tabs-id6012_fd5905-97 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id6012_fd5905-97 > .kt-tabs-title-list li .kt-tab-title:hover, .wp-block-kadence-tabs .kt-tabs-id6012_fd5905-97 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title:hover{border-color:var(u002du002dglobal-palette7, #eeeeee);color:var(u002du002dglobal-palette5, #444444);background:var(u002du002dglobal-palette9, #ffffff);}.wp-block-kadence-tabs .kt-tabs-id6012_fd5905-97 > .kt-tabs-title-list li.kt-tab-title-active .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id6012_fd5905-97 > .kt-tabs-content-wrap > .kt-tabs-accordion-title.kt-tab-title-active .kt-tab-title{border-color:#0a6689;color:#0a6689;background:var(u002du002dglobal-palette9, #ffffff);}@media all and (max-width: 1024px){.kt-tabs-id6012_fd5905-97 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:1px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid var(u002du002dglobal-palette7, #eeeeee);border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-tabs-id6012_fd5905-97 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:1px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid var(u002du002dglobal-palette7, #eeeeee);border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-tabs alignnone product-detail-tab\"><div class=\"kt-tabs-wrap kt-tabs-id6012_fd5905-97 kt-tabs-has-3-tabs kt-active-tab-1 kt-tabs-layout-tabs kt-tabs-tablet-layout-inherit kt-tabs-mobile-layout-tabs kt-tab-alignment-center \"><ul class=\"kt-tabs-title-list\"><li id=\"tab-modelsampspecs\" class=\"kt-title-item kt-title-item-1 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-active\"><a href=\"#tab-modelsampspecs\" data-tab=\"1\" class=\"kt-tab-title kt-tab-title-1 \"><span class=\"kt-title-text\">Models &amp; Specs<\/span><\/a><\/li><li id=\"tab-customoptions\" class=\"kt-title-item kt-title-item-2 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-customoptions\" data-tab=\"2\" class=\"kt-tab-title kt-tab-title-2 \"><span class=\"kt-title-text\">Custom Options<\/span><\/a><\/li><li id=\"tab-casestudiesampvideos\" class=\"kt-title-item kt-title-item-3 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-casestudiesampvideos\" data-tab=\"3\" class=\"kt-tab-title kt-tab-title-3 \"><span class=\"kt-title-text\">Case Studies &amp; Videos<\/span><\/a><\/li><\/ul><div class=\"kt-tabs-content-wrap\"><div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-1 kt-inner-tab_4439ce-a3\"><div class=\"kt-tab-inner-content-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading6012_39b118-01, .wp-block-kadence-advancedheading.kt-adv-heading6012_39b118-01[data-kb-block=\"kb-adv-heading6012_39b118-01\"]{display:block;margin-top:var(--global-kb-spacing-sm, 1.5rem);font-size:1.5rem;font-style:normal;color:#949aa3;}.wp-block-kadence-advancedheading.kt-adv-heading6012_39b118-01 mark, .wp-block-kadence-advancedheading.kt-adv-heading6012_39b118-01[data-kb-block=\"kb-adv-heading6012_39b118-01\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading6012_39b118-01 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6012_39b118-01\"><strong> G-V11 Electric Articulating Boom Lifts<\/strong><\/span>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6012_e6bb3a-d7, .wp-block-kadence-advancedheading.kt-adv-heading6012_e6bb3a-d7[data-kb-block=\"kb-adv-heading6012_e6bb3a-d7\"]{padding-bottom:0px;margin-top:1rem;margin-bottom:3rem;font-size:4rem;line-height:1;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading6012_e6bb3a-d7 mark, .wp-block-kadence-advancedheading.kt-adv-heading6012_e6bb3a-d7[data-kb-block=\"kb-adv-heading6012_e6bb3a-d7\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading6012_e6bb3a-d7, .wp-block-kadence-advancedheading.kt-adv-heading6012_e6bb3a-d7[data-kb-block=\"kb-adv-heading6012_e6bb3a-d7\"]{font-size:2.3rem;}}<\/style>\n<h2 class=\"kt-adv-heading6012_e6bb3a-d7 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6012_e6bb3a-d7\">Models &amp; Specs<\/h2>\n\n<style>.kb-row-layout-id6012_418c14-fd > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6012_418c14-fd > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6012_418c14-fd > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id6012_418c14-fd > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6012_418c14-fd > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id6012_418c14-fd > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6012_418c14-fd alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column6012_495c87-ac > .kt-inside-inner-col,.kadence-column6012_495c87-ac > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_495c87-ac > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_495c87-ac > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_495c87-ac > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_495c87-ac > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_495c87-ac{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_495c87-ac > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_495c87-ac > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_495c87-ac\"><div class=\"kt-inside-inner-col\"><figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td colspan=\"2\"><strong>Specifications<\/strong><\/td><\/tr><tr><td>Max. Working height<\/td><td>12.52m<\/td><\/tr><tr><td>Max. Platform height<\/td><td>10.52m<\/td><\/tr><tr><td>Max. up and over clearance<\/td><td>4.65m<\/td><\/tr><tr><td>Max. Working radius<\/td><td>6.5m<\/td><\/tr><tr><td>\u24b6&nbsp;Platform width<\/td><td>0.7m<\/td><\/tr><tr><td>\u24b7&nbsp;Platform length<\/td><td>1.4m<\/td><\/tr><tr><td>\u24b8&nbsp;Height \u2013 stowed<\/td><td>2.0m<\/td><\/tr><tr><td>\u24b9&nbsp;Length&nbsp;\u2013 stowed<\/td><td>5.6m<\/td><\/tr><tr><td>\u24ba&nbsp;Width<\/td><td>1.5m<\/td><\/tr><tr><td>\u24bb&nbsp;Wheelbase<\/td><td>1.95m<\/td><\/tr><tr><td>Ground clearance \u2013 center<\/td><td>0.14m<\/td><\/tr><\/tbody><\/table><\/figure><\/div><\/div>\n\n<style>.kadence-column6012_dd939f-7a > .kt-inside-inner-col,.kadence-column6012_dd939f-7a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_dd939f-7a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_dd939f-7a > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_dd939f-7a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_dd939f-7a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_dd939f-7a{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_dd939f-7a > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_dd939f-7a > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_dd939f-7a\"><div class=\"kt-inside-inner-col\"><figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td colspan=\"2\"><strong>Productivity<\/strong><\/td><\/tr><tr><td>Max. Lift capacity<\/td><td>200kg<\/td><\/tr><tr><td>Number of platform occupants<\/td><td>2<\/td><\/tr><tr><td>Platform rotation<\/td><td>\u00b180\u00b0<\/td><\/tr><tr><td>Turntable rotation<\/td><td>355\u00b0<\/td><\/tr><tr><td>Vertical jib rotation (up\/down)<\/td><td>\u00b170\u00b0<\/td><\/tr><tr><td>Drive speed \u2013 stowed<\/td><td>4.8km\/h<\/td><\/tr><tr><td>Gradeability \u2013 stowed<\/td><td>35%<\/td><\/tr><tr><td>Max. Working angle (Tilt sensor activation)<\/td><td>3\u00b0<\/td><\/tr><tr><td>Turning radius (outside)<\/td><td>4.08m<\/td><\/tr><tr><td>Drive and steer<\/td><td>2\u00d72<\/td><\/tr><tr><td>Weight<\/td><td>5200kg<\/td><\/tr><\/tbody><\/table><\/figure><\/div><\/div>\n<\/div><\/div>\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td colspan=\"2\"><strong>Power<\/strong><\/td><\/tr><tr><td>Battery<\/td><td>48V\/320Ah<\/td><\/tr><tr><td>Control voltage<\/td><td>24V<\/td><\/tr><tr><td>Pump motor<\/td><td>4kw<\/td><\/tr><tr><td>Drive motor<\/td><td>3.3kw<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<style>.kb-row-layout-id6012_378fc0-ab > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6012_378fc0-ab > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6012_378fc0-ab > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:4rem;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6012_378fc0-ab > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6012_378fc0-ab > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6012_378fc0-ab > .kt-row-column-wrap{padding-top:3rem;padding-right:1rem;padding-left:1rem;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6012_378fc0-ab alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column6012_856868-b3 > .kt-inside-inner-col,.kadence-column6012_856868-b3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_856868-b3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_856868-b3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_856868-b3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_856868-b3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_856868-b3{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_856868-b3 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_856868-b3 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_856868-b3\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id6012_8c710e-39 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6012_8c710e-39 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6012_8c710e-39 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6012_8c710e-39 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6012_8c710e-39 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6012_8c710e-39 > .kt-row-column-wrap{padding-top:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6012_8c710e-39 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column6012_2112b2-3f > .kt-inside-inner-col{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid #eeeeee;border-left:0px solid transparent;}.kadence-column6012_2112b2-3f > .kt-inside-inner-col,.kadence-column6012_2112b2-3f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_2112b2-3f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_2112b2-3f > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_2112b2-3f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_2112b2-3f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_2112b2-3f{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_2112b2-3f > .kt-inside-inner-col{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid #eeeeee;border-left:0px solid transparent;flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_2112b2-3f > .kt-inside-inner-col{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid #eeeeee;border-left:0px solid transparent;flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_2112b2-3f application-section-title\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading6012_82360a-66, .wp-block-kadence-advancedheading.kt-adv-heading6012_82360a-66[data-kb-block=\"kb-adv-heading6012_82360a-66\"]{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);font-size:2.8rem;font-weight:700;font-style:normal;border-bottom:3px solid var(--global-palette8, #F7FAFC);}.wp-block-kadence-advancedheading.kt-adv-heading6012_82360a-66 mark, .wp-block-kadence-advancedheading.kt-adv-heading6012_82360a-66[data-kb-block=\"kb-adv-heading6012_82360a-66\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading6012_82360a-66, .wp-block-kadence-advancedheading.kt-adv-heading6012_82360a-66[data-kb-block=\"kb-adv-heading6012_82360a-66\"]{border-bottom:3px solid var(--global-palette8, #F7FAFC);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading6012_82360a-66, .wp-block-kadence-advancedheading.kt-adv-heading6012_82360a-66[data-kb-block=\"kb-adv-heading6012_82360a-66\"]{font-size:1.7rem;border-bottom:3px solid var(--global-palette8, #F7FAFC);}}<\/style>\n<h2 class=\"kt-adv-heading6012_82360a-66 section-title-h2 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading6012_82360a-66\">Features<\/h2><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n<style>.kb-row-layout-id6012_9107a3-b1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6012_9107a3-b1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6012_9107a3-b1 > .kt-row-column-wrap{column-gap:2rem;row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id6012_9107a3-b1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6012_9107a3-b1 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id6012_9107a3-b1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6012_9107a3-b1 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column6012_ac43ac-c8 > .kt-inside-inner-col{padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column6012_ac43ac-c8 > .kt-inside-inner-col,.kadence-column6012_ac43ac-c8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_ac43ac-c8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_ac43ac-c8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_ac43ac-c8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_ac43ac-c8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_ac43ac-c8{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_ac43ac-c8 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_ac43ac-c8 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_ac43ac-c8\"><div class=\"kt-inside-inner-col\"><figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.quentinlifts.com\/wp-content\/uploads\/2024\/07\/2024071232.png\" alt=\"\" class=\"wp-image-14223\"\/><\/figure>\n\n<p style=\"padding-top:1rem;padding-bottom:1rem\">The product is lightweight and energy-saving, and has compact design with excellent battery life.<\/p><\/div><\/div>\n\n<style>.kadence-column6012_9984e1-08 > .kt-inside-inner-col{padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column6012_9984e1-08 > .kt-inside-inner-col,.kadence-column6012_9984e1-08 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_9984e1-08 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_9984e1-08 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_9984e1-08 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_9984e1-08 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_9984e1-08{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_9984e1-08 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_9984e1-08 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_9984e1-08\"><div class=\"kt-inside-inner-col\"><figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.quentinlifts.com\/wp-content\/uploads\/2024\/07\/2024071226.png\" alt=\"\" class=\"wp-image-14224\"\/><\/figure>\n\n<p style=\"padding-top:1rem;padding-bottom:1rem\">\u03a3-shaped boom with compact structure and flexible extension can realize vertical lifting and horizontal extension, and has strong obstacle-surpassing ability.<\/p><\/div><\/div>\n\n<style>.kadence-column6012_3fab18-60 > .kt-inside-inner-col{padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column6012_3fab18-60 > .kt-inside-inner-col,.kadence-column6012_3fab18-60 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_3fab18-60 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_3fab18-60 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_3fab18-60 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_3fab18-60 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_3fab18-60{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_3fab18-60 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_3fab18-60 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_3fab18-60\"><div class=\"kt-inside-inner-col\"><figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.quentinlifts.com\/wp-content\/uploads\/2024\/07\/2024071265.png\" alt=\"\" class=\"wp-image-14225\"\/><\/figure>\n\n<p style=\"padding-top:1rem;padding-bottom:1rem\">160\u00b0 rotatable platform provides a larger working range, while the narrow turntable with compact layout improves work efficiency.<\/p><\/div><\/div>\n\n<style>.kadence-column6012_20f451-28 > .kt-inside-inner-col,.kadence-column6012_20f451-28 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_20f451-28 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_20f451-28 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_20f451-28 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_20f451-28 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_20f451-28{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_20f451-28 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_20f451-28 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_20f451-28\"><div class=\"kt-inside-inner-col\"><figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.quentinlifts.com\/wp-content\/uploads\/2024\/07\/2024071262.png\" alt=\"\" class=\"wp-image-14226\"\/><\/figure>\n\n<p style=\"padding-top:1rem;padding-bottom:1rem\">The platform control panel is PG and Bosch Rexroth brand, which is the same as the ground control. User-friendly design with safety factors considered ensures a reliable work performance.<\/p><\/div><\/div>\n\n<style>.kadence-column6012_4cb71d-fb > .kt-inside-inner-col,.kadence-column6012_4cb71d-fb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_4cb71d-fb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_4cb71d-fb > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_4cb71d-fb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_4cb71d-fb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_4cb71d-fb{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_4cb71d-fb > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_4cb71d-fb > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_4cb71d-fb\"><div class=\"kt-inside-inner-col\"><figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.quentinlifts.com\/wp-content\/uploads\/2024\/07\/2024071244.png\" alt=\"\" class=\"wp-image-14229\"\/><\/figure>\n\n<p style=\"padding-top:1rem;padding-bottom:1rem\">International brand drag chain of the telescopic jib provides safety protection and guiding capabilities for the cables inside the booms and prolongs the service life of the cables.<\/p><\/div><\/div>\n\n<style>.kadence-column6012_338fa3-cc > .kt-inside-inner-col,.kadence-column6012_338fa3-cc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_338fa3-cc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_338fa3-cc > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_338fa3-cc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_338fa3-cc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_338fa3-cc{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_338fa3-cc > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_338fa3-cc > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_338fa3-cc\"><div class=\"kt-inside-inner-col\"><figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.quentinlifts.com\/wp-content\/uploads\/2024\/07\/2024071252.png\" alt=\"\" class=\"wp-image-14227\"\/><\/figure>\n\n<p style=\"padding-top:1rem;padding-bottom:1rem\">Equipped with solid tires, skid-proof and explosion-proof with longer lifetime, providing a stable and labor-saving operation.<\/p><\/div><\/div>\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6012_a85e68-f2, .wp-block-kadence-advancedheading.kt-adv-heading6012_a85e68-f2[data-kb-block=\"kb-adv-heading6012_a85e68-f2\"]{padding-bottom:0px;margin-top:1rem;margin-bottom:3rem;font-size:4rem;line-height:1;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading6012_a85e68-f2 mark, .wp-block-kadence-advancedheading.kt-adv-heading6012_a85e68-f2[data-kb-block=\"kb-adv-heading6012_a85e68-f2\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading6012_a85e68-f2, .wp-block-kadence-advancedheading.kt-adv-heading6012_a85e68-f2[data-kb-block=\"kb-adv-heading6012_a85e68-f2\"]{font-size:2.3rem;}}<\/style>\n<h2 class=\"kt-adv-heading6012_a85e68-f2 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6012_a85e68-f2\">Videos<\/h2>\n\n<style>.kb-row-layout-id6012_b24fcf-44 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6012_b24fcf-44 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6012_b24fcf-44 > .kt-row-column-wrap{column-gap:2.5rem;row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id6012_b24fcf-44 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6012_b24fcf-44 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id6012_b24fcf-44 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6012_b24fcf-44 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column6012_15496d-22 > .kt-inside-inner-col,.kadence-column6012_15496d-22 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_15496d-22 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_15496d-22 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_15496d-22 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_15496d-22 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_15496d-22{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_15496d-22 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_15496d-22 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_15496d-22\"><div class=\"kt-inside-inner-col\"><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Electric Articulating Boom Lifts - usage of platform constrol system\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/BQtnyvWZXns?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><strong>Usage of Platform Constrol System<\/strong><\/figcaption><\/figure><\/div><\/div>\n\n<style>.kadence-column6012_1881b4-3d > .kt-inside-inner-col,.kadence-column6012_1881b4-3d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_1881b4-3d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_1881b4-3d > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_1881b4-3d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_1881b4-3d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_1881b4-3d{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_1881b4-3d > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_1881b4-3d > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_1881b4-3d\"><div class=\"kt-inside-inner-col\"><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Electric Articulating Boom Lifts - Walking and Lifting\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/FWo14DVvtMM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><strong>Walking and Lifting<\/strong><\/figcaption><\/figure><\/div><\/div>\n\n<style>.kadence-column6012_d2687e-de > .kt-inside-inner-col,.kadence-column6012_d2687e-de > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_d2687e-de > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_d2687e-de > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_d2687e-de > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_d2687e-de > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_d2687e-de{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_d2687e-de > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_d2687e-de > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_d2687e-de\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6012_bf7150-47, .wp-block-kadence-advancedheading.kt-adv-heading6012_bf7150-47[data-kb-block=\"kb-adv-heading6012_bf7150-47\"]{padding-bottom:0px;margin-top:1rem;margin-bottom:3rem;font-size:4rem;line-height:1;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading6012_bf7150-47 mark, .wp-block-kadence-advancedheading.kt-adv-heading6012_bf7150-47[data-kb-block=\"kb-adv-heading6012_bf7150-47\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading6012_bf7150-47, .wp-block-kadence-advancedheading.kt-adv-heading6012_bf7150-47[data-kb-block=\"kb-adv-heading6012_bf7150-47\"]{font-size:2.3rem;}}<\/style>\n<h2 class=\"kt-adv-heading6012_bf7150-47 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6012_bf7150-47\">Diagram<\/h2>\n\n<style>.kb-row-layout-id6012_8b7f52-01 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6012_8b7f52-01 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6012_8b7f52-01 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, calc(60% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(40% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id6012_8b7f52-01 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6012_8b7f52-01 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id6012_8b7f52-01 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6012_8b7f52-01 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column6012_793a33-0f > .kt-inside-inner-col,.kadence-column6012_793a33-0f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_793a33-0f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_793a33-0f > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_793a33-0f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_793a33-0f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_793a33-0f{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_793a33-0f > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_793a33-0f > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_793a33-0f\"><div class=\"kt-inside-inner-col\"><style>.kb-image6012_f7c3ae-3b .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image6012_f7c3ae-3b size-large\"><a href=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-2.png\" class=\"kb-advanced-image-link\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"435\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-2-1024x435.png\" alt=\"\" class=\"kb-img wp-image-6002\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-2-1024x435.png 1024w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-2-300x127.png 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-2-768x326.png 768w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-2-1536x653.png 1536w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-2-18x8.png 18w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-2-600x255.png 600w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-2.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n<style>.kb-image6012_5b0035-13 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image6012_5b0035-13 size-large\"><a href=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram.png\" class=\"kb-advanced-image-link\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"331\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-1024x331.png\" alt=\"\" class=\"kb-img wp-image-6004\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-1024x331.png 1024w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-300x97.png 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-768x248.png 768w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-1536x496.png 1536w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-18x6.png 18w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-600x194.png 600w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div><\/div>\n\n<style>.kadence-column6012_cbfd74-d8 > .kt-inside-inner-col,.kadence-column6012_cbfd74-d8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_cbfd74-d8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_cbfd74-d8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_cbfd74-d8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_cbfd74-d8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_cbfd74-d8{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_cbfd74-d8 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_cbfd74-d8 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_cbfd74-d8\"><div class=\"kt-inside-inner-col\"><style>.kb-image6012_43dde0-2c .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image6012_43dde0-2c size-full\"><a href=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-3.png\" class=\"kb-advanced-image-link\"><img loading=\"lazy\" decoding=\"async\" width=\"656\" height=\"795\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-3.png\" alt=\"\" class=\"kb-img wp-image-6003\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-3.png 656w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-3-248x300.png 248w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-3-10x12.png 10w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2025\/01\/Electric-Articulating-Boom-Lift-Diagram-3-600x727.png 600w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><\/a><\/figure><\/div><\/div>\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6012_d29e51-d5, .wp-block-kadence-advancedheading.kt-adv-heading6012_d29e51-d5[data-kb-block=\"kb-adv-heading6012_d29e51-d5\"]{padding-bottom:0px;margin-top:1rem;margin-bottom:3rem;font-size:4rem;line-height:1;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading6012_d29e51-d5 mark, .wp-block-kadence-advancedheading.kt-adv-heading6012_d29e51-d5[data-kb-block=\"kb-adv-heading6012_d29e51-d5\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading6012_d29e51-d5, .wp-block-kadence-advancedheading.kt-adv-heading6012_d29e51-d5[data-kb-block=\"kb-adv-heading6012_d29e51-d5\"]{font-size:2.3rem;}}<\/style>\n<h2 class=\"kt-adv-heading6012_d29e51-d5 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6012_d29e51-d5\">Other Boom Lifts<\/h2>\n\n<div data-block-name=\"woocommerce\/product-tag\" data-columns=\"4\" data-content-visibility=\"{&quot;image&quot;:true,&quot;title&quot;:true,&quot;price&quot;:false,&quot;rating&quot;:false,&quot;button&quot;:false}\" data-tags=\"[200]\" class=\"wc-block-grid wp-block-product-tag wc-block-product-tag has-4-columns has-multiple-rows\"><ul class=\"wc-block-grid__products\"><li class=\"wc-block-grid__product entry loop-entry content-bg woo-archive-action-on-hover woo-archive-btn-text product-loop-unboxed woo-archive-image-hover-none\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/gtk-10-10m-simple-articulated-boom-lift\/\" class=\"wc-block-grid__product-link woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/GTK-12-Simple-Boom-Lift-768x574-1-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/GTK-12-Simple-Boom-Lift-768x574-1-300x300.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/GTK-12-Simple-Boom-Lift-768x574-1-150x150.webp 150w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/GTK-12-Simple-Boom-Lift-768x574-1-100x100.webp 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"product-details content-bg entry-content-wrap\">\n\t\t\t\t\t<a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/gtk-10-10m-simple-articulated-boom-lift\/\" class=\"wc-block-grid__product-title-link\">\n\t\t\t\t\t\t<div class=\"wc-block-grid__product-title\">GTK-10 10m Simple\u00a0Articulated Boom Lift<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product entry loop-entry content-bg woo-archive-action-on-hover woo-archive-btn-text product-loop-unboxed woo-archive-image-hover-none\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/gtk-12-12m-simple-articulated-boom-lift\/\" class=\"wc-block-grid__product-link woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/GTK-12-12m-Simple-Articulated-Boom-Lift-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/GTK-12-12m-Simple-Articulated-Boom-Lift-300x300.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/GTK-12-12m-Simple-Articulated-Boom-Lift-150x150.webp 150w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/GTK-12-12m-Simple-Articulated-Boom-Lift-100x100.webp 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"product-details content-bg entry-content-wrap\">\n\t\t\t\t\t<a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/gtk-12-12m-simple-articulated-boom-lift\/\" class=\"wc-block-grid__product-title-link\">\n\t\t\t\t\t\t<div class=\"wc-block-grid__product-title\">GTK-12 12m Simple\u00a0Articulated Boom Lift<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product entry loop-entry content-bg woo-archive-action-on-hover woo-archive-btn-text product-loop-unboxed woo-archive-image-hover-none\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/gtk-14-14m-simple-articulated-boom-lift\/\" class=\"wc-block-grid__product-link woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/GTK-14-14m-Simple-Articulated-Boom-Lift-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/GTK-14-14m-Simple-Articulated-Boom-Lift-300x300.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/GTK-14-14m-Simple-Articulated-Boom-Lift-150x150.webp 150w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/GTK-14-14m-Simple-Articulated-Boom-Lift-100x100.webp 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"product-details content-bg entry-content-wrap\">\n\t\t\t\t\t<a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/gtk-14-14m-simple-articulated-boom-lift\/\" class=\"wc-block-grid__product-title-link\">\n\t\t\t\t\t\t<div class=\"wc-block-grid__product-title\">GTK-14 14m Simple\u00a0Articulated Boom Lift<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product entry loop-entry content-bg woo-archive-action-on-hover woo-archive-btn-text product-loop-unboxed woo-archive-image-hover-none\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/g-rz22-diesel-articulating-boom-lift\/\" class=\"wc-block-grid__product-link woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024080971-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024080971-300x300.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024080971-150x150.webp 150w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024080971-100x100.webp 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"product-details content-bg entry-content-wrap\">\n\t\t\t\t\t<a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/g-rz22-diesel-articulating-boom-lift\/\" class=\"wc-block-grid__product-title-link\">\n\t\t\t\t\t\t<div class=\"wc-block-grid__product-title\">G-RZ22 Diesel Articulating Boom Lift<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product entry loop-entry content-bg woo-archive-action-on-hover woo-archive-btn-text product-loop-unboxed woo-archive-image-hover-none\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/g-rz26-diesel-articulating-boom-lift\/\" class=\"wc-block-grid__product-link woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024080959-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024080959-300x300.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024080959-150x150.webp 150w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024080959-100x100.webp 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"product-details content-bg entry-content-wrap\">\n\t\t\t\t\t<a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/g-rz26-diesel-articulating-boom-lift\/\" class=\"wc-block-grid__product-title-link\">\n\t\t\t\t\t\t<div class=\"wc-block-grid__product-title\">G-RZ26 Diesel Articulating Boom Lift<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product entry loop-entry content-bg woo-archive-action-on-hover woo-archive-btn-text product-loop-unboxed woo-archive-image-hover-none\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/g-rz28-diesel-articulating-boom-lift\/\" class=\"wc-block-grid__product-link woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/202408093-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/202408093-300x300.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/202408093-150x150.webp 150w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/202408093-100x100.webp 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"product-details content-bg entry-content-wrap\">\n\t\t\t\t\t<a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/g-rz28-diesel-articulating-boom-lift\/\" class=\"wc-block-grid__product-title-link\">\n\t\t\t\t\t\t<div class=\"wc-block-grid__product-title\">G-RZ28 Diesel Articulating Boom Lift<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product entry loop-entry content-bg woo-archive-action-on-hover woo-archive-btn-text product-loop-unboxed woo-archive-image-hover-none\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/16m-electric-telescopic-boom-lifts\/\" class=\"wc-block-grid__product-link woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071610-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071610-300x300.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071610-150x150.webp 150w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071610-100x100.webp 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"product-details content-bg entry-content-wrap\">\n\t\t\t\t\t<a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/16m-electric-telescopic-boom-lifts\/\" class=\"wc-block-grid__product-title-link\">\n\t\t\t\t\t\t<div class=\"wc-block-grid__product-title\">16m Electric Telescopic Boom Lifts<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product entry loop-entry content-bg woo-archive-action-on-hover woo-archive-btn-text product-loop-unboxed woo-archive-image-hover-none\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/18m-electric-telescopic-boom-lifts\/\" class=\"wc-block-grid__product-link woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071610-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071610-300x300.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071610-150x150.webp 150w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071610-100x100.webp 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"product-details content-bg entry-content-wrap\">\n\t\t\t\t\t<a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/18m-electric-telescopic-boom-lifts\/\" class=\"wc-block-grid__product-title-link\">\n\t\t\t\t\t\t<div class=\"wc-block-grid__product-title\">18m Electric Telescopic Boom Lifts<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product entry loop-entry content-bg woo-archive-action-on-hover woo-archive-btn-text product-loop-unboxed woo-archive-image-hover-none\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/20m-electric-telescopic-boom-lifts\/\" class=\"wc-block-grid__product-link woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071727-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071727-300x300.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071727-150x150.webp 150w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071727-100x100.webp 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"product-details content-bg entry-content-wrap\">\n\t\t\t\t\t<a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/20m-electric-telescopic-boom-lifts\/\" class=\"wc-block-grid__product-title-link\">\n\t\t\t\t\t\t<div class=\"wc-block-grid__product-title\">20m Electric Telescopic Boom Lifts<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product entry loop-entry content-bg woo-archive-action-on-hover woo-archive-btn-text product-loop-unboxed woo-archive-image-hover-none\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/24m-electric-telescopic-boom-lifts\/\" class=\"wc-block-grid__product-link woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071750-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071750-300x300.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071750-150x150.webp 150w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071750-100x100.webp 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"product-details content-bg entry-content-wrap\">\n\t\t\t\t\t<a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/24m-electric-telescopic-boom-lifts\/\" class=\"wc-block-grid__product-title-link\">\n\t\t\t\t\t\t<div class=\"wc-block-grid__product-title\">24m Electric Telescopic Boom Lifts<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product entry loop-entry content-bg woo-archive-action-on-hover woo-archive-btn-text product-loop-unboxed woo-archive-image-hover-none\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/26m-electric-telescopic-boom-lifts\/\" class=\"wc-block-grid__product-link woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071750-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071750-300x300.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071750-150x150.webp 150w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071750-100x100.webp 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"product-details content-bg entry-content-wrap\">\n\t\t\t\t\t<a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/26m-electric-telescopic-boom-lifts\/\" class=\"wc-block-grid__product-title-link\">\n\t\t\t\t\t\t<div class=\"wc-block-grid__product-title\">26m Electric Telescopic Boom Lifts<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product entry loop-entry content-bg woo-archive-action-on-hover woo-archive-btn-text product-loop-unboxed woo-archive-image-hover-none\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/20m-electric-articulating-boom-lifts\/\" class=\"wc-block-grid__product-link woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071259-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071259-300x300.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071259-150x150.webp 150w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071259-100x100.webp 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"product-details content-bg entry-content-wrap\">\n\t\t\t\t\t<a href=\"https:\/\/www.gradinlifts.com\/ko\/product\/20m-electric-articulating-boom-lifts\/\" class=\"wc-block-grid__product-title-link\">\n\t\t\t\t\t\t<div class=\"wc-block-grid__product-title\">20m Electric Articulating Boom Lifts<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/li><\/ul><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6012_e5a5ab-35, .wp-block-kadence-advancedheading.kt-adv-heading6012_e5a5ab-35[data-kb-block=\"kb-adv-heading6012_e5a5ab-35\"]{padding-bottom:0px;margin-top:1rem;margin-bottom:3rem;font-size:4rem;line-height:1;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading6012_e5a5ab-35 mark, .wp-block-kadence-advancedheading.kt-adv-heading6012_e5a5ab-35[data-kb-block=\"kb-adv-heading6012_e5a5ab-35\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading6012_e5a5ab-35, .wp-block-kadence-advancedheading.kt-adv-heading6012_e5a5ab-35[data-kb-block=\"kb-adv-heading6012_e5a5ab-35\"]{font-size:2.3rem;}}<\/style>\n<h2 class=\"kt-adv-heading6012_e5a5ab-35 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6012_e5a5ab-35\">FAQ<\/h2>\n\n<style>.kt-accordion-id6012_f850ea-a9 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id6012_f850ea-a9 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id6012_f850ea-a9 .wp-block-kadence-pane .kt-accordion-header-wrap .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;color:#555555;padding-top:10px;padding-right:14px;padding-bottom:10px;padding-left:14px;}.kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id6012_f850ea-a9 .kt-accordion-header-wrap .kt-blocks-accordion-header:hover, body:not(.hide-focus-outline) .kt-accordion-id6012_f850ea-a9 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus{color:#444444;background:#eeeeee;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:focus .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:focus .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:focus .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id6012_f850ea-a9 .kt-accordion-header-wrap .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#444444;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6012_f850ea-a9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#444444;}@media all and (max-width: 1024px){.kt-accordion-id6012_f850ea-a9 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id6012_f850ea-a9 .wp-block-kadence-pane .kt-accordion-header-wrap .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id6012_f850ea-a9 .kt-accordion-header-wrap .kt-blocks-accordion-header:hover, body:not(.hide-focus-outline) .kt-accordion-id6012_f850ea-a9 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id6012_f850ea-a9 .kt-accordion-header-wrap .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id6012_f850ea-a9 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id6012_f850ea-a9 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id6012_f850ea-a9 .wp-block-kadence-pane .kt-accordion-header-wrap .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}.kt-accordion-id6012_f850ea-a9 .kt-accordion-header-wrap .kt-blocks-accordion-header:hover, body:not(.hide-focus-outline) .kt-accordion-id6012_f850ea-a9 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id6012_f850ea-a9 .kt-accordion-header-wrap .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id6012_f850ea-a9 kt-accordion-has-8-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"0\"><div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane6012_017e2e-05\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What is an electric articulating boom lift?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><p>An <strong>Electric Articulating Boom Lift<\/strong> is a type of aerial lift that features a jointed or articulated arm, allowing it to reach elevated work areas with flexibility and precision. Here are some key characteristics:<\/p>\n\n<ol class=\"wp-block-list\"><li><strong>Design<\/strong>: The boom consists of multiple sections that can pivot, which enables it to extend over obstacles and reach heights that straight boom lifts might not be able to access.<\/li>\n\n<li><strong>Electric Power<\/strong>: As the name suggests, these lifts are powered by electricity, making them quieter and more environmentally friendly compared to their diesel counterparts. They are ideal for indoor use or in noise-sensitive areas.<\/li>\n\n<li><strong>Height and Reach<\/strong>: Electric articulating boom lifts can typically reach heights ranging from 30 to over 60 feet, depending on the model. Their articulated joints allow for extended reach and versatility.<\/li>\n\n<li><strong>Applications<\/strong>: Commonly used in construction, maintenance, and repair work, these lifts are excellent for tasks like painting, installing fixtures, or working on overhead structures.<\/li>\n\n<li><strong>Safety Features<\/strong>: Most models come equipped with safety features such as guardrails, emergency stop buttons, and stability systems to prevent tipping.<\/li><\/ol><\/div><\/div><\/div>\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane6012_14160a-5e\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What is the difference between a boom lift and an articulating lift?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><p>The main differences between a <strong>boom lift<\/strong> and an <strong>articulating lift<\/strong> lie in their design, functionality, and applications. Here\u2019s a breakdown:<\/p>\n\n<h3 class=\"wp-block-heading\">Boom Lift<\/h3>\n\n<ul class=\"wp-block-list\"><li><strong>Design<\/strong>: A boom lift typically features a long, straight arm (or boom) that extends vertically or horizontally.<\/li>\n\n<li><strong>Types<\/strong>: Boom lifts can be either straight (also known as telescopic) or articulating, but the term &#8220;boom lift&#8221; often refers to the straight type.<\/li>\n\n<li><strong>Reach<\/strong>: These lifts are ideal for reaching high, vertical spaces quickly and directly, making them suitable for tasks like building maintenance, construction, and outdoor applications.<\/li>\n\n<li><strong>Stability<\/strong>: Boom lifts generally offer more stability at greater heights due to their linear design.<\/li><\/ul>\n\n<h3 class=\"wp-block-heading\">Articulating Lift<\/h3>\n\n<ul class=\"wp-block-list\"><li><strong>Design<\/strong>: An articulating lift has a jointed arm that can bend at one or more points, allowing it to navigate around obstacles and reach over difficult terrain.<\/li>\n\n<li><strong>Flexibility<\/strong>: The articulated design provides greater flexibility and maneuverability, making it easier to access tight or elevated spaces, especially in urban environments.<\/li>\n\n<li><strong>Use Cases<\/strong>: Commonly used for tasks that require reaching over barriers or obstacles, such as tree trimming, maintenance of buildings with overhangs, and indoor applications where space is limited.<\/li><\/ul><\/div><\/div><\/div>\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane6012_775ca6-e3\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What is the difference between electric and gas boom lifts?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><h3 class=\"wp-block-heading\">Electric Boom Lifts<\/h3>\n\n<ol class=\"wp-block-list\"><li><strong>Power Source<\/strong>: Powered by electric batteries, making them quieter and emissions-free during operation.<\/li>\n\n<li><strong>Applications<\/strong>: Ideal for indoor use or in areas where noise and emissions are concerns, such as warehouses, shopping malls, and sensitive environments.<\/li>\n\n<li><strong>Performance<\/strong>:<ul class=\"wp-block-list\"><li><strong>Run Time<\/strong>: Limited by battery life, which can vary based on usage and the model&#8217;s specifications.<\/li>\n\n<li><strong>Speed<\/strong>: Generally slower in terms of lifting and lowering speeds compared to gas models.<\/li>\n\n<li><strong>Stability<\/strong>: Often designed for a lower center of gravity, enhancing stability.<\/li><\/ul><\/li>\n\n<li><strong>Maintenance<\/strong>: Typically requires less maintenance since there are fewer moving parts compared to gas engines.<\/li>\n\n<li><strong>Cost<\/strong>: Usually have a lower upfront cost and lower operational costs due to reduced fuel requirements.<\/li><\/ol>\n\n<h3 class=\"wp-block-heading\">Gas Boom Lifts<\/h3>\n\n<ol class=\"wp-block-list\"><li><strong>Power Source<\/strong>: Powered by gasoline or diesel engines, providing more robust power for heavier lifting.<\/li>\n\n<li><strong>Applications<\/strong>: Suitable for outdoor use, particularly in construction sites or rugged terrains where mobility and power are essential.<\/li>\n\n<li><strong>Performance<\/strong>:<ul class=\"wp-block-list\"><li><strong>Run Time<\/strong>: Can operate for longer periods without the need to recharge, as they can refuel quickly.<\/li>\n\n<li><strong>Speed<\/strong>: Often faster in terms of lifting and maneuvering, making them suitable for high-demand jobs.<\/li>\n\n<li><strong>Terrain Handling<\/strong>: Better suited for rough or uneven surfaces due to larger tires and more powerful engines.<\/li><\/ul><\/li>\n\n<li><strong>Maintenance<\/strong>: May require more frequent maintenance due to the complexity of gas engines.<\/li>\n\n<li><strong>Cost<\/strong>: Generally have higher fuel and maintenance costs compared to electric models.<\/li><\/ol><\/div><\/div><\/div>\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane6012_7659fb-09\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What is the difference between electric and diesel boom lift?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><h3 class=\"wp-block-heading\">Electric Boom Lifts<\/h3>\n\n<ol class=\"wp-block-list\"><li><strong>Power Source<\/strong>:<ul class=\"wp-block-list\"><li>Powered by electric batteries.<\/li>\n\n<li>Emission-free during operation, producing no exhaust fumes.<\/li><\/ul><\/li>\n\n<li><strong>Applications<\/strong>:<ul class=\"wp-block-list\"><li>Ideal for indoor use, such as in warehouses, manufacturing facilities, and shopping malls.<\/li>\n\n<li>Suitable for noise-sensitive environments.<\/li><\/ul><\/li>\n\n<li><strong>Performance<\/strong>:<ul class=\"wp-block-list\"><li><strong>Run Time<\/strong>: Limited by battery life; may require recharging after extended use.<\/li>\n\n<li><strong>Speed<\/strong>: Generally operates at slower lifting and maneuvering speeds compared to diesel models.<\/li>\n\n<li><strong>Stability<\/strong>: Often designed for a lower center of gravity, enhancing stability in lighter loads.<\/li><\/ul><\/li>\n\n<li><strong>Maintenance<\/strong>:<ul class=\"wp-block-list\"><li>Generally requires less maintenance due to fewer moving parts compared to diesel engines.<\/li><\/ul><\/li>\n\n<li><strong>Cost<\/strong>:<ul class=\"wp-block-list\"><li>Typically lower initial costs and operational costs due to reduced fuel needs and maintenance.<\/li><\/ul><\/li><\/ol>\n\n<h3 class=\"wp-block-heading\">Diesel Boom Lifts<\/h3>\n\n<ol class=\"wp-block-list\"><li><strong>Power Source<\/strong>:<ul class=\"wp-block-list\"><li>Powered by diesel fuel engines, providing robust power for heavy lifting.<\/li>\n\n<li>Produces emissions and exhaust fumes during operation.<\/li><\/ul><\/li>\n\n<li><strong>Applications<\/strong>:<ul class=\"wp-block-list\"><li>Best suited for outdoor use, particularly on construction sites, rugged terrains, or areas requiring high mobility.<\/li>\n\n<li>Capable of handling rough and uneven ground conditions.<\/li><\/ul><\/li>\n\n<li><strong>Performance<\/strong>:<ul class=\"wp-block-list\"><li><strong>Run Time<\/strong>: Can operate for longer periods without the need to recharge; can refuel quickly.<\/li>\n\n<li><strong>Speed<\/strong>: Often faster in lifting and maneuvering, making them suitable for high-demand jobs.<\/li>\n\n<li><strong>Terrain Handling<\/strong>: Typically has larger tires and better traction, allowing them to navigate rough surfaces more effectively.<\/li><\/ul><\/li>\n\n<li><strong>Maintenance<\/strong>:<ul class=\"wp-block-list\"><li>May require more frequent maintenance due to the complexity of diesel engines and the need for fuel system upkeep.<\/li><\/ul><\/li>\n\n<li><strong>Cost<\/strong>:<ul class=\"wp-block-list\"><li>Generally higher fuel and maintenance costs compared to electric models.<\/li><\/ul><\/li><\/ol><\/div><\/div><\/div>\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane6012_cb957d-d5\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">How does the electric articulating boom lift work?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><p>An <strong>Electric Articulating Boom Lift<\/strong> operates through a combination of mechanical, hydraulic, and electrical systems to provide elevated access for various tasks. Here\u2019s how it works:<\/p>\n\n<h3 class=\"wp-block-heading\">Components<\/h3>\n\n<ol class=\"wp-block-list\"><li><strong>Boom Sections<\/strong>: The lift consists of multiple jointed sections (arms) that can bend and extend to reach different heights and positions.<\/li>\n\n<li><strong>Platform<\/strong>: A platform or basket at the end of the boom where operators stand to perform tasks.<\/li>\n\n<li><strong>Hydraulic System<\/strong>: This system controls the movement of the boom sections, allowing them to extend, retract, and pivot.<\/li>\n\n<li><strong>Electric Motor<\/strong>: Powers the hydraulic system and other electrical components, such as controls and safety systems.<\/li>\n\n<li><strong>Battery Pack<\/strong>: Provides the necessary power for the electric motor, typically rechargeable.<\/li><\/ol>\n\n<h3 class=\"wp-block-heading\">Operation<\/h3>\n\n<ol class=\"wp-block-list\"><li><strong>Powering Up<\/strong>: The operator starts the lift using controls located on the platform or ground level. The electric motor draws power from the battery pack.<\/li>\n\n<li><strong>Raising the Boom<\/strong>:<ul class=\"wp-block-list\"><li>The operator uses the controls to activate the hydraulic system.<\/li>\n\n<li>This system moves the boom sections into position, allowing them to articulate (bend) and extend vertically.<\/li><\/ul><\/li>\n\n<li><strong>Reaching Desired Height<\/strong>:<ul class=\"wp-block-list\"><li>The boom can be maneuvered to reach the desired height and position, often with the ability to swing the platform outwards to avoid obstacles.<\/li>\n\n<li>The articulated design allows for extensive reach and flexibility in navigating around barriers.<\/li><\/ul><\/li>\n\n<li><strong>Stabilization<\/strong>: Many models have stabilizers or outriggers that extend from the base to enhance stability when elevated.<\/li>\n\n<li><strong>Performing Tasks<\/strong>: Once at the desired height, operators can safely perform various tasks, such as maintenance, construction, or installation.<\/li>\n\n<li><strong>Lowering and Retracting<\/strong>: After completing the work, the operator uses controls to lower the boom back to the ground and retract it as needed.<\/li><\/ol><\/div><\/div><\/div>\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-6 kt-pane6012_c5f67e-b5\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What is an articulated boom lift used for?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><h3 class=\"wp-block-heading\">1. <strong>Maintenance and Repair<\/strong><\/h3>\n\n<ul class=\"wp-block-list\"><li><strong>Building Exteriors<\/strong>: Ideal for maintenance tasks on building facades, such as cleaning windows, painting, or repairing siding.<\/li>\n\n<li><strong>Roofing<\/strong>: Used for accessing rooftops for repairs, inspections, or installations.<\/li><\/ul>\n\n<h3 class=\"wp-block-heading\">2. <strong>Construction<\/strong><\/h3>\n\n<ul class=\"wp-block-list\"><li><strong>Framework Installation<\/strong>: Assists in installing structural elements, such as beams and trusses, in hard-to-reach areas.<\/li>\n\n<li><strong>Electrical and Plumbing Work<\/strong>: Provides access for the installation and maintenance of electrical and plumbing systems.<\/li><\/ul>\n\n<h3 class=\"wp-block-heading\">3. <strong>Tree Care and Landscaping<\/strong><\/h3>\n\n<ul class=\"wp-block-list\"><li><strong>Tree Trimming<\/strong>: Allows arborists to safely reach and trim high branches.<\/li>\n\n<li><strong>Landscaping<\/strong>: Used for installing outdoor lighting, signs, or other landscape features at height.<\/li><\/ul>\n\n<h3 class=\"wp-block-heading\">4. <strong>Event Setup<\/strong><\/h3>\n\n<ul class=\"wp-block-list\"><li><strong>Stage and Lighting Setup<\/strong>: Commonly used in the entertainment industry for setting up stages, lighting rigs, and sound equipment for concerts and events.<\/li><\/ul>\n\n<h3 class=\"wp-block-heading\">5. <strong>Warehousing and Inventory Management<\/strong><\/h3>\n\n<ul class=\"wp-block-list\"><li><strong>Stocking High Shelves<\/strong>: Used in warehouses to access high storage areas for inventory management or maintenance tasks.<\/li><\/ul>\n\n<h3 class=\"wp-block-heading\">6. <strong>Painting and Finishing<\/strong><\/h3>\n\n<ul class=\"wp-block-list\"><li><strong>Interior and Exterior Painting<\/strong>: Provides access to high walls and ceilings for painting, finishing, or decorative work.<\/li><\/ul>\n\n<h3 class=\"wp-block-heading\">7. <strong>Inspection and Surveys<\/strong><\/h3>\n\n<ul class=\"wp-block-list\"><li><strong>Structural Inspections<\/strong>: Used by inspectors to evaluate high structures, such as bridges, towers, and utility poles.<\/li><\/ul>\n\n<h3 class=\"wp-block-heading\">8. <strong>Installation of HVAC Systems<\/strong><\/h3>\n\n<ul class=\"wp-block-list\"><li><strong>Heating and Cooling Units<\/strong>: Facilitates the installation and maintenance of HVAC systems in elevated locations.<\/li><\/ul><\/div><\/div><\/div>\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-7 kt-pane6012_1e0c15-b3\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">How many types of boom lifts are there?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><p>The&nbsp;<strong>three<\/strong>&nbsp;types are telescopic boom lifts (straight boom lifts), articulating boom lifts (knuckle boom lifts) and trailer mounted knuckle booms.<\/p><\/div><\/div><\/div>\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-8 kt-pane6012_cc5260-b3\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What is the difference between a vertical lift and a boom lift?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><p>The height you need to reach will affect which types of aerial lifts you should consider.&nbsp;<strong>A telescoping boom lift can help you reach maximum heights, while scissor lifts or a vertical mast lift might be a better choice for lower applications<\/strong>.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-2 kt-inner-tab_12d9fc-b7\"><div class=\"kt-tab-inner-content-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading6012_d62536-58, .wp-block-kadence-advancedheading.kt-adv-heading6012_d62536-58[data-kb-block=\"kb-adv-heading6012_d62536-58\"]{display:block;margin-top:var(--global-kb-spacing-sm, 1.5rem);font-size:1.5rem;font-style:normal;color:#949aa3;}.wp-block-kadence-advancedheading.kt-adv-heading6012_d62536-58 mark, .wp-block-kadence-advancedheading.kt-adv-heading6012_d62536-58[data-kb-block=\"kb-adv-heading6012_d62536-58\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading6012_d62536-58 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6012_d62536-58\"><strong> G-V11 Electric Articulating Boom Lifts<\/strong><\/span>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6012_359826-47, .wp-block-kadence-advancedheading.kt-adv-heading6012_359826-47[data-kb-block=\"kb-adv-heading6012_359826-47\"]{padding-bottom:0px;margin-top:var(--global-kb-spacing-xs, 1rem);font-size:4rem;line-height:1;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading6012_359826-47 mark, .wp-block-kadence-advancedheading.kt-adv-heading6012_359826-47[data-kb-block=\"kb-adv-heading6012_359826-47\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading6012_359826-47 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6012_359826-47\">Custom Options<\/h2>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6012_28af6c-d3, .wp-block-kadence-advancedheading.kt-adv-heading6012_28af6c-d3[data-kb-block=\"kb-adv-heading6012_28af6c-d3\"]{margin-top:2rem;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading6012_28af6c-d3 mark, .wp-block-kadence-advancedheading.kt-adv-heading6012_28af6c-d3[data-kb-block=\"kb-adv-heading6012_28af6c-d3\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading6012_28af6c-d3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6012_28af6c-d3\"><strong>Customize Your Lifts<\/strong><\/p>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6012_245b47-ed, .wp-block-kadence-advancedheading.kt-adv-heading6012_245b47-ed[data-kb-block=\"kb-adv-heading6012_245b47-ed\"]{margin-bottom:2rem;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading6012_245b47-ed mark, .wp-block-kadence-advancedheading.kt-adv-heading6012_245b47-ed[data-kb-block=\"kb-adv-heading6012_245b47-ed\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading6012_245b47-ed wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6012_245b47-ed\">Specifically sized, configured, mobile, high-cycle, or automated &#8211; when you need a lift to perform a specific function, we have the materials, components, and design techniques to produce a one-of-a-kind lifting solution for your application.<\/p>\n\n<style>.kb-row-layout-id1399_f77cfe-72 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1399_f77cfe-72 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1399_f77cfe-72 > .kt-row-column-wrap{column-gap:0.5rem;row-gap:0.5rem;padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);padding-left:var(--global-kb-spacing-md, 2rem);grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id1399_f77cfe-72 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1399_f77cfe-72 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1399_f77cfe-72 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1399_f77cfe-72 alignnone custom-list wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1399_91757f-e4 > .kt-inside-inner-col{display:flex;}.kadence-column1399_91757f-e4 > .kt-inside-inner-col,.kadence-column1399_91757f-e4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_91757f-e4 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-md, 2rem);column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_91757f-e4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_91757f-e4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_91757f-e4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_91757f-e4{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_91757f-e4 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_91757f-e4 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_91757f-e4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_47b624-ff, .wp-block-kadence-advancedheading.kt-adv-heading1399_47b624-ff[data-kb-block=\"kb-adv-heading1399_47b624-ff\"]{margin-top:0px;text-align:left;font-style:normal;text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading1399_47b624-ff mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_47b624-ff[data-kb-block=\"kb-adv-heading1399_47b624-ff\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<div class=\"kt-adv-heading1399_47b624-ff wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_47b624-ff\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/controls\/\" data-type=\"design-options\" data-id=\"1251\" rel=\"nofollow\">controls<\/a><\/div><\/div><\/div>\n\n<style>.kadence-column1399_469127-dc > .kt-inside-inner-col,.kadence-column1399_469127-dc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_469127-dc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_469127-dc > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_469127-dc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_469127-dc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_469127-dc{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_469127-dc > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_469127-dc > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_469127-dc\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_f8ad1c-e7, .wp-block-kadence-advancedheading.kt-adv-heading1399_f8ad1c-e7[data-kb-block=\"kb-adv-heading1399_f8ad1c-e7\"]{margin-top:0px;text-align:left;font-style:normal;text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading1399_f8ad1c-e7 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_f8ad1c-e7[data-kb-block=\"kb-adv-heading1399_f8ad1c-e7\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<div class=\"kt-adv-heading1399_f8ad1c-e7 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_f8ad1c-e7\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/safety\/\" data-type=\"design-options\" data-id=\"1248\" rel=\"nofollow\">Safety<\/a><\/div><\/div><\/div>\n\n<style>.kadence-column1399_cca2dd-d9 > .kt-inside-inner-col,.kadence-column1399_cca2dd-d9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_cca2dd-d9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_cca2dd-d9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_cca2dd-d9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_cca2dd-d9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_cca2dd-d9{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_cca2dd-d9 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_cca2dd-d9 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_cca2dd-d9\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_16b45a-92, .wp-block-kadence-advancedheading.kt-adv-heading1399_16b45a-92[data-kb-block=\"kb-adv-heading1399_16b45a-92\"]{display:block;margin-top:0px;text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_16b45a-92 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_16b45a-92[data-kb-block=\"kb-adv-heading1399_16b45a-92\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_16b45a-92 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_16b45a-92\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/mobility\/\" data-type=\"design-options\" data-id=\"1250\" rel=\"nofollow\">Mobility<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_624850-62 > .kt-inside-inner-col,.kadence-column1399_624850-62 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_624850-62 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_624850-62 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_624850-62 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_624850-62 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_624850-62{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_624850-62 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_624850-62 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_624850-62\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_c8b213-1d, .wp-block-kadence-advancedheading.kt-adv-heading1399_c8b213-1d[data-kb-block=\"kb-adv-heading1399_c8b213-1d\"]{display:block;margin-top:0px;text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_c8b213-1d mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_c8b213-1d[data-kb-block=\"kb-adv-heading1399_c8b213-1d\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_c8b213-1d wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_c8b213-1d\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/platform-configurations\/\" data-type=\"design-options\" data-id=\"1253\" rel=\"nofollow\">Platform Configurations<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_559f6b-8e > .kt-inside-inner-col,.kadence-column1399_559f6b-8e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_559f6b-8e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_559f6b-8e > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_559f6b-8e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_559f6b-8e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_559f6b-8e{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_559f6b-8e > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_559f6b-8e > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_559f6b-8e\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_e587ca-a2, .wp-block-kadence-advancedheading.kt-adv-heading1399_e587ca-a2[data-kb-block=\"kb-adv-heading1399_e587ca-a2\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_e587ca-a2 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_e587ca-a2[data-kb-block=\"kb-adv-heading1399_e587ca-a2\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_e587ca-a2 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_e587ca-a2\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/platform-shuttle\/\" data-type=\"design-options\" data-id=\"1254\" rel=\"nofollow\">Platform Shuttle<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_80f33a-0a > .kt-inside-inner-col,.kadence-column1399_80f33a-0a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_80f33a-0a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_80f33a-0a > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_80f33a-0a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_80f33a-0a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_80f33a-0a{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_80f33a-0a > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_80f33a-0a > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_80f33a-0a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_65206b-69, .wp-block-kadence-advancedheading.kt-adv-heading1399_65206b-69[data-kb-block=\"kb-adv-heading1399_65206b-69\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading1399_65206b-69 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_65206b-69[data-kb-block=\"kb-adv-heading1399_65206b-69\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_65206b-69 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_65206b-69\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/tilt\/\" data-type=\"design-options\" data-id=\"1255\" rel=\"nofollow\">Tilt<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_887e6b-6d > .kt-inside-inner-col,.kadence-column1399_887e6b-6d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_887e6b-6d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_887e6b-6d > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_887e6b-6d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_887e6b-6d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_887e6b-6d{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_887e6b-6d > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_887e6b-6d > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_887e6b-6d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_f2f2c1-7d, .wp-block-kadence-advancedheading.kt-adv-heading1399_f2f2c1-7d[data-kb-block=\"kb-adv-heading1399_f2f2c1-7d\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_f2f2c1-7d mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_f2f2c1-7d[data-kb-block=\"kb-adv-heading1399_f2f2c1-7d\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_f2f2c1-7d wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_f2f2c1-7d\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/turn-rotate\/\" data-type=\"design-options\" data-id=\"1256\" rel=\"nofollow\">Turn &amp; Rotate<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_9cefde-3e > .kt-inside-inner-col,.kadence-column1399_9cefde-3e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_9cefde-3e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_9cefde-3e > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_9cefde-3e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_9cefde-3e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_9cefde-3e{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_9cefde-3e > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_9cefde-3e > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_9cefde-3e\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_928ab4-55, .wp-block-kadence-advancedheading.kt-adv-heading1399_928ab4-55[data-kb-block=\"kb-adv-heading1399_928ab4-55\"]{display:block;margin-top:0px;text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_928ab4-55 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_928ab4-55[data-kb-block=\"kb-adv-heading1399_928ab4-55\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_928ab4-55 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_928ab4-55\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/conveyors\/\" data-type=\"design-options\" data-id=\"1257\" rel=\"nofollow\">Conveyors<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_09e0e5-f1 > .kt-inside-inner-col,.kadence-column1399_09e0e5-f1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_09e0e5-f1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_09e0e5-f1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_09e0e5-f1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_09e0e5-f1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_09e0e5-f1{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_09e0e5-f1 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_09e0e5-f1 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_09e0e5-f1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_793b51-c9, .wp-block-kadence-advancedheading.kt-adv-heading1399_793b51-c9[data-kb-block=\"kb-adv-heading1399_793b51-c9\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_793b51-c9 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_793b51-c9[data-kb-block=\"kb-adv-heading1399_793b51-c9\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_793b51-c9 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_793b51-c9\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/high-travel\/\" data-type=\"design-options\" data-id=\"1258\" rel=\"nofollow\">High Travel<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_bebf5f-e4 > .kt-inside-inner-col,.kadence-column1399_bebf5f-e4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_bebf5f-e4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_bebf5f-e4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_bebf5f-e4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_bebf5f-e4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_bebf5f-e4{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_bebf5f-e4 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_bebf5f-e4 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_bebf5f-e4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_c107d0-e9, .wp-block-kadence-advancedheading.kt-adv-heading1399_c107d0-e9[data-kb-block=\"kb-adv-heading1399_c107d0-e9\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading1399_c107d0-e9 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_c107d0-e9[data-kb-block=\"kb-adv-heading1399_c107d0-e9\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_c107d0-e9 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_c107d0-e9\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/high-capacity\/\" data-type=\"design-options\" data-id=\"1259\" rel=\"nofollow\">High Capacity<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_d033e7-2b > .kt-inside-inner-col,.kadence-column1399_d033e7-2b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_d033e7-2b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_d033e7-2b > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_d033e7-2b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_d033e7-2b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_d033e7-2b{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_d033e7-2b > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_d033e7-2b > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_d033e7-2b\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_4094d0-c9, .wp-block-kadence-advancedheading.kt-adv-heading1399_4094d0-c9[data-kb-block=\"kb-adv-heading1399_4094d0-c9\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_4094d0-c9 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_4094d0-c9[data-kb-block=\"kb-adv-heading1399_4094d0-c9\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_4094d0-c9 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_4094d0-c9\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/automation\/\" data-type=\"design-options\" data-id=\"1260\" rel=\"nofollow\">Automation<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_2a63f8-3f > .kt-inside-inner-col,.kadence-column1399_2a63f8-3f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_2a63f8-3f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_2a63f8-3f > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_2a63f8-3f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_2a63f8-3f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_2a63f8-3f{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_2a63f8-3f > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_2a63f8-3f > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_2a63f8-3f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_4ca036-02, .wp-block-kadence-advancedheading.kt-adv-heading1399_4ca036-02[data-kb-block=\"kb-adv-heading1399_4ca036-02\"]{display:block;margin-top:0px;text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_4ca036-02 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_4ca036-02[data-kb-block=\"kb-adv-heading1399_4ca036-02\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_4ca036-02 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_4ca036-02\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/actuation\/\" data-type=\"design-options\" data-id=\"1261\" rel=\"nofollow\">Actuation<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_8654a1-35 > .kt-inside-inner-col,.kadence-column1399_8654a1-35 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_8654a1-35 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_8654a1-35 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_8654a1-35 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_8654a1-35 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_8654a1-35{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_8654a1-35 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_8654a1-35 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_8654a1-35\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_6a5600-9c, .wp-block-kadence-advancedheading.kt-adv-heading1399_6a5600-9c[data-kb-block=\"kb-adv-heading1399_6a5600-9c\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_6a5600-9c mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_6a5600-9c[data-kb-block=\"kb-adv-heading1399_6a5600-9c\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_6a5600-9c wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_6a5600-9c\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/lift-deflection\/\" data-type=\"design-options\" data-id=\"1262\" rel=\"nofollow\">Lift Deflection<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_4e6f8d-6e > .kt-inside-inner-col,.kadence-column1399_4e6f8d-6e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_4e6f8d-6e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_4e6f8d-6e > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_4e6f8d-6e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_4e6f8d-6e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_4e6f8d-6e{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_4e6f8d-6e > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_4e6f8d-6e > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_4e6f8d-6e\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_e64250-d2, .wp-block-kadence-advancedheading.kt-adv-heading1399_e64250-d2[data-kb-block=\"kb-adv-heading1399_e64250-d2\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading1399_e64250-d2 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_e64250-d2[data-kb-block=\"kb-adv-heading1399_e64250-d2\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_e64250-d2 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_e64250-d2\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/speed\/\" data-type=\"design-options\" data-id=\"1263\" rel=\"nofollow\">Speed<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_89c9bd-2d > .kt-inside-inner-col,.kadence-column1399_89c9bd-2d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_89c9bd-2d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_89c9bd-2d > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_89c9bd-2d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_89c9bd-2d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_89c9bd-2d{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_89c9bd-2d > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_89c9bd-2d > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_89c9bd-2d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_61cd62-6f, .wp-block-kadence-advancedheading.kt-adv-heading1399_61cd62-6f[data-kb-block=\"kb-adv-heading1399_61cd62-6f\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_61cd62-6f mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_61cd62-6f[data-kb-block=\"kb-adv-heading1399_61cd62-6f\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_61cd62-6f wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_61cd62-6f\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/indexing\/\" data-type=\"design-options\" data-id=\"1264\" rel=\"nofollow\">Indexing<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_312355-57 > .kt-inside-inner-col,.kadence-column1399_312355-57 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_312355-57 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_312355-57 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_312355-57 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_312355-57 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_312355-57{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_312355-57 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_312355-57 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_312355-57\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_0136e9-03, .wp-block-kadence-advancedheading.kt-adv-heading1399_0136e9-03[data-kb-block=\"kb-adv-heading1399_0136e9-03\"]{display:block;margin-top:0px;text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_0136e9-03 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_0136e9-03[data-kb-block=\"kb-adv-heading1399_0136e9-03\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_0136e9-03 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_0136e9-03\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/locking-pins-devices\/\" data-type=\"design-options\" data-id=\"1265\" rel=\"nofollow\">Locking Pins &amp; Devices<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_9cc590-14 > .kt-inside-inner-col,.kadence-column1399_9cc590-14 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_9cc590-14 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_9cc590-14 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_9cc590-14 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_9cc590-14 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_9cc590-14{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_9cc590-14 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_9cc590-14 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_9cc590-14\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_2e58e3-3d, .wp-block-kadence-advancedheading.kt-adv-heading1399_2e58e3-3d[data-kb-block=\"kb-adv-heading1399_2e58e3-3d\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_2e58e3-3d mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_2e58e3-3d[data-kb-block=\"kb-adv-heading1399_2e58e3-3d\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_2e58e3-3d wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_2e58e3-3d\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/power-units\/\" data-type=\"design-options\" data-id=\"1266\" rel=\"nofollow\">Power Units<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_b0d1ce-84 > .kt-inside-inner-col,.kadence-column1399_b0d1ce-84 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_b0d1ce-84 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_b0d1ce-84 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_b0d1ce-84 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_b0d1ce-84 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_b0d1ce-84{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_b0d1ce-84 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_b0d1ce-84 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_b0d1ce-84\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_d1850b-98, .wp-block-kadence-advancedheading.kt-adv-heading1399_d1850b-98[data-kb-block=\"kb-adv-heading1399_d1850b-98\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading1399_d1850b-98 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_d1850b-98[data-kb-block=\"kb-adv-heading1399_d1850b-98\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_d1850b-98 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_d1850b-98\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/load-weighing-measuring\/\" data-type=\"design-options\" data-id=\"1269\" rel=\"nofollow\">Measuring<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_e6d752-60 > .kt-inside-inner-col,.kadence-column1399_e6d752-60 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_e6d752-60 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_e6d752-60 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_e6d752-60 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_e6d752-60 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_e6d752-60{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_e6d752-60 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_e6d752-60 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_e6d752-60\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_0ce192-cb, .wp-block-kadence-advancedheading.kt-adv-heading1399_0ce192-cb[data-kb-block=\"kb-adv-heading1399_0ce192-cb\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_0ce192-cb mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_0ce192-cb[data-kb-block=\"kb-adv-heading1399_0ce192-cb\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_0ce192-cb wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_0ce192-cb\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/materials-surfaces-coatings\/\" data-type=\"design-options\" data-id=\"1267\" rel=\"nofollow\">Materials &amp; Surfaces<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_9e9320-c9 > .kt-inside-inner-col,.kadence-column1399_9e9320-c9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_9e9320-c9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_9e9320-c9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_9e9320-c9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_9e9320-c9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_9e9320-c9{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_9e9320-c9 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_9e9320-c9 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_9e9320-c9\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_c59851-61, .wp-block-kadence-advancedheading.kt-adv-heading1399_c59851-61[data-kb-block=\"kb-adv-heading1399_c59851-61\"]{display:block;margin-top:0px;text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_c59851-61 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_c59851-61[data-kb-block=\"kb-adv-heading1399_c59851-61\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_c59851-61 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_c59851-61\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/gates-enclosures-guard-rails\/\" data-type=\"design-options\" data-id=\"1268\" rel=\"nofollow\">Gates &amp; Enclosures <\/a><\/span><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-3 kt-inner-tab_2418de-92\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id6012_93026e-0c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6012_93026e-0c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6012_93026e-0c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6012_93026e-0c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6012_93026e-0c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6012_93026e-0c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6012_93026e-0c alignnone cases-list-title product-detail-title2 wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column6012_af244a-a7 > .kt-inside-inner-col,.kadence-column6012_af244a-a7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_af244a-a7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_af244a-a7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_af244a-a7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_af244a-a7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_af244a-a7{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_af244a-a7 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_af244a-a7 > .kt-inside-inner-col{flex-direction:column;}}.kadence-column6012_af244a-a7 {ndisplay: inline-block;n}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_af244a-a7\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading6012_8f3093-7b, .wp-block-kadence-advancedheading.kt-adv-heading6012_8f3093-7b[data-kb-block=\"kb-adv-heading6012_8f3093-7b\"]{margin-top:2rem;font-size:2rem;line-height:1;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6012_8f3093-7b mark, .wp-block-kadence-advancedheading.kt-adv-heading6012_8f3093-7b[data-kb-block=\"kb-adv-heading6012_8f3093-7b\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading6012_8f3093-7b, .wp-block-kadence-advancedheading.kt-adv-heading6012_8f3093-7b[data-kb-block=\"kb-adv-heading6012_8f3093-7b\"]{font-size:1.3rem;}}<\/style>\n<h2 class=\"kt-adv-heading6012_8f3093-7b case-title2 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6012_8f3093-7b\">Lift Product Videos<\/h2><\/div><\/div>\n<\/div><\/div>\n\n<style>.kb-row-layout-id6012_0ea4b8-5d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6012_0ea4b8-5d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6012_0ea4b8-5d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:100%;margin-left:auto;margin-right:auto;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6012_0ea4b8-5d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6012_0ea4b8-5d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6012_0ea4b8-5d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6012_0ea4b8-5d alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column6012_654754-3c > .kt-inside-inner-col,.kadence-column6012_654754-3c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_654754-3c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_654754-3c > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_654754-3c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_654754-3c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_654754-3c{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_654754-3c > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_654754-3c, .kt-inside-inner-col > .kadence-column6012_654754-3c:not(.specificity){margin-right:0%;}.kadence-column6012_654754-3c > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_654754-3c\"><div class=\"kt-inside-inner-col\"><style>.kt-post-loop6012_c670e0-6f .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop6012_c670e0-6f .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop6012_c670e0-6f .kt-blocks-post-grid-item{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;overflow:hidden;}.kt-post-loop6012_c670e0-6f .kt-blocks-post-grid-item header{padding-top:5px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop6012_c670e0-6f .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:24px;line-height:30px;}.kt-post-loop6012_c670e0-6f .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#777777;}.kt-post-loop6012_c670e0-6f .kt-blocks-post-grid-item .kt-blocks-post-top-meta a{color:#777777;}.kt-post-loop6012_c670e0-6f .kt-blocks-post-grid-item .kt-blocks-post-top-meta a:hover{color:#444444;}.kt-post-loop6012_c670e0-6f .entry-content{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop6012_c670e0-6f .kt-blocks-post-footer{color:#777777;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:12px;line-height:20px;}.kt-post-loop6012_c670e0-6f .entry-content:after{height:0px;}.kt-post-loop6012_c670e0-6f .kt-blocks-post-footer a{color:#777777;}.kt-post-loop6012_c670e0-6f .kt-blocks-post-footer a:hover{color:#444444;}.kt-post-loop6012_c670e0-6f .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kt-post-loop6012_c670e0-6f .kt-blocks-post-grid-item{border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;}}@media all and (max-width: 767px){.kt-post-loop6012_c670e0-6f .kt-blocks-post-grid-item{border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;}}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop6012_c670e0-6f kt-post-grid-layout-grid  videos-main\"><div class=\"kt-post-grid-layout-grid-wrap kt-post-grid-wrap\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"data-item-selector=\".kt-post-masonry-item\"><article class=\"kt-blocks-post-grid-item post-5535 video type-video status-publish has-post-thumbnail hentry tag-heavy-duty tag-hydraulic tag-scissor-lift tag-track-mounted product_category-scissor-lift-tables application_category-logistics application_category-manufacturing\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/video\/track-mounted-hydraulic-lifting-platform\/\" aria-label=\"Read More Track-Mounted Hydraulic Lifting Platform\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/11\/Track-Mounted-Hydraulic-Lifting-Platform-4.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/11\/Track-Mounted-Hydraulic-Lifting-Platform-4.webp 600w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/11\/Track-Mounted-Hydraulic-Lifting-Platform-4-225x300.webp 225w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/11\/Track-Mounted-Hydraulic-Lifting-Platform-4-9x12.webp 9w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/video\/track-mounted-hydraulic-lifting-platform\/\">Track-Mounted Hydraulic Lifting Platform<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>\ud0dc\uadf8<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/heavy-duty\/\" rel=\"tag\">Heavy Duty<\/a>, <a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/hydraulic\/\" rel=\"tag\">Hydraulic<\/a>, <a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/scissor-lift\/\" rel=\"tag\">scissor lift<\/a>, <a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/track-mounted\/\" rel=\"tag\">Track-Mounted<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4377 video type-video status-publish has-post-thumbnail hentry tag-fixed tag-hydraulic product_category-scissor-lift-tables application_category-aerospace\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/video\/fixed-scissor-lift-for-aerospace\/\" aria-label=\"Read More Fixed Scissor Lift for Aerospace\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"933\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Fixed-Scissor-Lift-for-Aerospace.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Fixed-Scissor-Lift-for-Aerospace.webp 700w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Fixed-Scissor-Lift-for-Aerospace-225x300.webp 225w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Fixed-Scissor-Lift-for-Aerospace-600x800.webp 600w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/video\/fixed-scissor-lift-for-aerospace\/\">Fixed Scissor Lift for Aerospace<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>\ud0dc\uadf8<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/fixed\/\" rel=\"tag\">Fixed<\/a>, <a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/hydraulic\/\" rel=\"tag\">Hydraulic<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-4279 video type-video status-publish has-post-thumbnail hentry tag-hydraulic tag-self-propelled product_category-scissor-lift-tables application_category-manufacturing\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/video\/self-propelled-hydraulic-scissor-lift\/\" aria-label=\"Read More Self-propelled Hydraulic Scissor Lift\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Self-propelled-Hydraulic-Scissor-Lift-3-576x1024.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Self-propelled-Hydraulic-Scissor-Lift-3-576x1024.webp 576w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Self-propelled-Hydraulic-Scissor-Lift-3-169x300.webp 169w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Self-propelled-Hydraulic-Scissor-Lift-3-600x1066.webp 600w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Self-propelled-Hydraulic-Scissor-Lift-3.webp 700w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/video\/self-propelled-hydraulic-scissor-lift\/\">Self-propelled Hydraulic Scissor Lift<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>\ud0dc\uadf8<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/hydraulic\/\" rel=\"tag\">Hydraulic<\/a>, <a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/self-propelled\/\" rel=\"tag\">Self Propelled<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-3750 video type-video status-publish has-post-thumbnail hentry tag-battery-electric tag-scissor-lift tag-self-propelled tag-small tag-tracked product_category-scissor-lift-tables\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/video\/tracked-scissor-lift\/\" aria-label=\"Read More Tracked Scissor Lift\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/07\/Tracked-Scissor-Lift-5-2.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/07\/Tracked-Scissor-Lift-5-2.webp 800w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/07\/Tracked-Scissor-Lift-5-2-300x225.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/07\/Tracked-Scissor-Lift-5-2-768x576.webp 768w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/07\/Tracked-Scissor-Lift-5-2-600x450.webp 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/video\/tracked-scissor-lift\/\">Tracked Scissor Lift<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>\ud0dc\uadf8<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/battery-electric\/\" rel=\"tag\">Battery Electric<\/a>, <a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/scissor-lift\/\" rel=\"tag\">scissor lift<\/a>, <a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/self-propelled\/\" rel=\"tag\">Self Propelled<\/a>, <a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/small\/\" rel=\"tag\">Small<\/a>, <a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/tracked\/\" rel=\"tag\">Tracked<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-3715 video type-video status-publish has-post-thumbnail hentry tag-battery-electric tag-scissor-lift tag-self-propelled tag-small product_category-scissor-lift-tables\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/video\/self-driven-battery-electric-scissor-lift\/\" aria-label=\"Read More Self-driven Battery Electric Scissor Lift\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"855\" height=\"479\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/07\/Self-driven-Battery-Electric-Scissor-Lift.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/07\/Self-driven-Battery-Electric-Scissor-Lift.webp 855w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/07\/Self-driven-Battery-Electric-Scissor-Lift-300x168.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/07\/Self-driven-Battery-Electric-Scissor-Lift-768x430.webp 768w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/07\/Self-driven-Battery-Electric-Scissor-Lift-600x336.webp 600w\" sizes=\"(max-width: 855px) 100vw, 855px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/video\/self-driven-battery-electric-scissor-lift\/\">Self-driven Battery Electric Scissor Lift<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>\ud0dc\uadf8<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/battery-electric\/\" rel=\"tag\">Battery Electric<\/a>, <a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/scissor-lift\/\" rel=\"tag\">scissor lift<\/a>, <a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/self-propelled\/\" rel=\"tag\">Self Propelled<\/a>, <a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/small\/\" rel=\"tag\">Small<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-3657 video type-video status-publish has-post-thumbnail hentry tag-hydraulic tag-scissor-lift product_category-scissor-lift-tables\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/video\/electric-hydraulic-lift-table\/\" aria-label=\"Read More Electric Hydraulic Lift Table\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"854\" height=\"480\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/07\/Hydraulic-Lift-Table.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/07\/Hydraulic-Lift-Table.webp 854w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/07\/Hydraulic-Lift-Table-300x169.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/07\/Hydraulic-Lift-Table-768x432.webp 768w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/07\/Hydraulic-Lift-Table-600x337.webp 600w\" sizes=\"(max-width: 854px) 100vw, 854px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/video\/electric-hydraulic-lift-table\/\">Electric Hydraulic Lift Table<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>\ud0dc\uadf8<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/hydraulic\/\" rel=\"tag\">Hydraulic<\/a>, <a href=\"https:\/\/www.gradinlifts.com\/ko\/tag\/scissor-lift\/\" rel=\"tag\">scissor lift<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/div><div class=\"kt-blocks-page-nav\">\n\t<nav class=\"navigation pagination\" aria-label=\"\uae00\">\n\t\t<h2 class=\"screen-reader-text\">\uae00 \ub0b4\ube44\uac8c\uc774\uc158<\/h2>\n\t\t<div class=\"nav-links\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/product\/6012\/page\/2\/\">2<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/product\/6012\/page\/2\/\"><span class=\"screen-reader-text\">Next Page<\/span><svg style=\"display:inline-block;vertical-align:middle\" aria-hidden=\"true\" class=\"kt-blocks-pagination-right-svg\" viewBox=\"0 0 320 512\" height=\"14\" width=\"8\" fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/a><\/div>\n\t<\/nav><\/div><\/div><!-- .wp-block-kadence-postgrid -->\n\n<style>.kb-row-layout-id6012_f8860a-90 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6012_f8860a-90 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6012_f8860a-90 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6012_f8860a-90 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6012_f8860a-90 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6012_f8860a-90 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6012_f8860a-90 alignnone cases-list-title product-detail-title2 wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column6012_985f37-df > .kt-inside-inner-col,.kadence-column6012_985f37-df > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6012_985f37-df > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6012_985f37-df > .kt-inside-inner-col{flex-direction:column;}.kadence-column6012_985f37-df > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6012_985f37-df > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6012_985f37-df{position:relative;}@media all and (max-width: 1024px){.kadence-column6012_985f37-df > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column6012_985f37-df > .kt-inside-inner-col{flex-direction:column;}}.kadence-column6012_985f37-df {ndisplay: inline-block;n}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6012_985f37-df\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading6012_085150-4e, .wp-block-kadence-advancedheading.kt-adv-heading6012_085150-4e[data-kb-block=\"kb-adv-heading6012_085150-4e\"]{margin-top:3rem;font-size:2rem;line-height:1;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6012_085150-4e mark, .wp-block-kadence-advancedheading.kt-adv-heading6012_085150-4e[data-kb-block=\"kb-adv-heading6012_085150-4e\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading6012_085150-4e, .wp-block-kadence-advancedheading.kt-adv-heading6012_085150-4e[data-kb-block=\"kb-adv-heading6012_085150-4e\"]{font-size:1.3rem;}}<\/style>\n<h2 class=\"kt-adv-heading6012_085150-4e case-title2 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6012_085150-4e\">Customized Cases<\/h2>\n\n<style>.kt-post-loop6012_d08b14-1d .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop6012_d08b14-1d .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop6012_d08b14-1d .kt-blocks-post-grid-item{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:1px solid currentColor;border-right:1px solid currentColor;border-bottom:1px solid currentColor;border-left:1px solid currentColor;overflow:hidden;}.kt-post-loop6012_d08b14-1d .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:15px;padding-right:25px;padding-bottom:25px;padding-left:25px;}.kt-post-loop6012_d08b14-1d .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop6012_d08b14-1d .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:24px;line-height:30px;}.kt-post-loop6012_d08b14-1d .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#777777;}.kt-post-loop6012_d08b14-1d .kt-blocks-post-grid-item .kt-blocks-post-top-meta a{color:#777777;}.kt-post-loop6012_d08b14-1d .kt-blocks-post-grid-item .kt-blocks-post-top-meta a:hover{color:#444444;}.kt-post-loop6012_d08b14-1d .entry-content{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop6012_d08b14-1d .kt-blocks-post-footer{color:#777777;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:12px;line-height:20px;}.kt-post-loop6012_d08b14-1d .entry-content:after{height:0px;}.kt-post-loop6012_d08b14-1d .kt-blocks-post-footer a{color:#777777;}.kt-post-loop6012_d08b14-1d .kt-blocks-post-footer a:hover{color:#444444;}.kt-post-loop6012_d08b14-1d .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kt-post-loop6012_d08b14-1d .kt-blocks-post-grid-item{border-top:1px solid currentColor;border-right:1px solid currentColor;border-bottom:1px solid currentColor;border-left:1px solid currentColor;}}@media all and (max-width: 767px){.kt-post-loop6012_d08b14-1d .kt-blocks-post-grid-item{border-top:1px solid currentColor;border-right:1px solid currentColor;border-bottom:1px solid currentColor;border-left:1px solid currentColor;}}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop6012_d08b14-1d kt-post-grid-layout-grid \"><div class=\"kt-post-grid-layout-grid-wrap kt-post-grid-wrap\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"data-item-selector=\".kt-post-masonry-item\"><article class=\"kt-blocks-post-grid-item post-7058 case type-case status-publish has-post-thumbnail hentry product_category-freight-lifts-vrc application_category-clothing application_category-manufacturing\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/fork-type-vertical-lifter-export-to-brazil-textile-logistics-automation-case-study\/\" aria-label=\"Read More Fork-Type Vertical Lifter Export to Brazil | Textile Logistics Automation Case Study\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"573\" height=\"1024\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Fork-Type-Vertical-Lifter-Export-to-Brazil-Textile-Logistics-Automation-Case-Study-2-1-573x1024.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Fork-Type-Vertical-Lifter-Export-to-Brazil-Textile-Logistics-Automation-Case-Study-2-1-573x1024.webp 573w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Fork-Type-Vertical-Lifter-Export-to-Brazil-Textile-Logistics-Automation-Case-Study-2-1-168x300.webp 168w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Fork-Type-Vertical-Lifter-Export-to-Brazil-Textile-Logistics-Automation-Case-Study-2-1-768x1372.webp 768w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Fork-Type-Vertical-Lifter-Export-to-Brazil-Textile-Logistics-Automation-Case-Study-2-1-7x12.webp 7w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Fork-Type-Vertical-Lifter-Export-to-Brazil-Textile-Logistics-Automation-Case-Study-2-1-600x1072.webp 600w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Fork-Type-Vertical-Lifter-Export-to-Brazil-Textile-Logistics-Automation-Case-Study-2-1.webp 774w\" sizes=\"(max-width: 573px) 100vw, 573px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/fork-type-vertical-lifter-export-to-brazil-textile-logistics-automation-case-study\/\">Fork-Type Vertical Lifter Export to Brazil | Textile Logistics Automation Case Study<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Custom fork-type vertical lifter XBT-4.28-0.03 engineered for Shanghai Textile Decoration Co., Ltd., exported to Brazil with Profinet integration and roller conveyor loop. 100 cartons\/hr, 45-day delivery. Full specs and FAQ included.<\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-7042 case type-case status-publish has-post-thumbnail hentry product_category-freight-lifts-vrc application_category-equipment-manufacturing application_category-manufacturing\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/heavy-duty-guide-rail-freight-lift-for-sinotruk-factory\/\" aria-label=\"Read More Heavy-Duty Guide Rail Freight Lift for SINOTRUK Factory\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Heavy-Duty-Guide-Rail-Freight-Lift-for-SINOTRUK-Factory-5-576x1024.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Heavy-Duty-Guide-Rail-Freight-Lift-for-SINOTRUK-Factory-5-576x1024.webp 576w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Heavy-Duty-Guide-Rail-Freight-Lift-for-SINOTRUK-Factory-5-169x300.webp 169w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Heavy-Duty-Guide-Rail-Freight-Lift-for-SINOTRUK-Factory-5-7x12.webp 7w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Heavy-Duty-Guide-Rail-Freight-Lift-for-SINOTRUK-Factory-5-600x1066.webp 600w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Heavy-Duty-Guide-Rail-Freight-Lift-for-SINOTRUK-Factory-5.webp 700w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/heavy-duty-guide-rail-freight-lift-for-sinotruk-factory\/\">Heavy-Duty Guide Rail Freight Lift for SINOTRUK Factory<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Gradin Lifts\n designed and manufactured two custom hydraulic guide rail freight lifts with a 4-meter lifting height, 1000kg capacity, and large 3000\u00d73000mm platform configuration. The project focused on maximizing loading efficiency while maintaining high structural stability inside a heavy industrial environment.<\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-6993 case type-case status-publish has-post-thumbnail hentry product_category-freight-lifts-vrc application_category-automotive\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/triplespeed-hydraulic-lift-auto-parts-plant-case\/\" aria-label=\"Read More Triple\u2011Speed Hydraulic Lift\uff5c14m Travel from 500mm Shallow Pit\uff5cAuto Parts Plant Case\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"558\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Triple-Speed-Hydraulic-Lift-14m-Travel-from-500mm-Shallow-Pit-06.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Triple-Speed-Hydraulic-Lift-14m-Travel-from-500mm-Shallow-Pit-06.webp 1000w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Triple-Speed-Hydraulic-Lift-14m-Travel-from-500mm-Shallow-Pit-06-300x167.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Triple-Speed-Hydraulic-Lift-14m-Travel-from-500mm-Shallow-Pit-06-768x429.webp 768w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Triple-Speed-Hydraulic-Lift-14m-Travel-from-500mm-Shallow-Pit-06-18x10.webp 18w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Triple-Speed-Hydraulic-Lift-14m-Travel-from-500mm-Shallow-Pit-06-600x335.webp 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/triplespeed-hydraulic-lift-auto-parts-plant-case\/\">Triple\u2011Speed Hydraulic Lift\uff5c14m Travel from 500mm Shallow Pit\uff5cAuto Parts Plant Case<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Custom triple\u2011speed guide rail lift for Beijing Jiacheng Xingye (Tier 1 supplier to Great Wall Motors &#038; Beijing Hyundai). Achieves 14m lift height from only 500mm pit depth. Three\u2011floor roller door interlock, mechanical fall arrest, 20\u2011day urgent delivery. Ideal for injection moulding &#038; foaming line material handling. Read the case study.<\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-6981 case type-case status-publish has-post-thumbnail hentry product_category-freight-lifts-vrc application_category-food-pharmaceutical\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/food-plant-freight-lift-5m-travel-from-350mm-shallow-pit\/\" aria-label=\"Read More Food Plant Freight Lift\uff5cSeamless Stainless Steel Car\uff5c4.5m Travel from 350mm Shallow Pit\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Food-Plant-Freight-Lift-4.5m-Travel-from-350mm-Shallow-Pit-1-576x1024.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Food-Plant-Freight-Lift-4.5m-Travel-from-350mm-Shallow-Pit-1-576x1024.webp 576w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Food-Plant-Freight-Lift-4.5m-Travel-from-350mm-Shallow-Pit-1-169x300.webp 169w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Food-Plant-Freight-Lift-4.5m-Travel-from-350mm-Shallow-Pit-1-7x12.webp 7w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Food-Plant-Freight-Lift-4.5m-Travel-from-350mm-Shallow-Pit-1-600x1066.webp 600w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/Food-Plant-Freight-Lift-4.5m-Travel-from-350mm-Shallow-Pit-1.webp 700w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/food-plant-freight-lift-5m-travel-from-350mm-shallow-pit\/\">Food Plant Freight Lift\uff5cSeamless Stainless Steel Car\uff5c4.5m Travel from 350mm Shallow Pit<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Two custom hydraulic guide rail lifts for a multinational food group\u2018s production base: full 304 stainless steel cars with seamless welding, 2:1 speed cylinders achieving 4.5m travel from a 350mm shallow pit, triple interlock (door\u2011platform\u2011pusher), 1.5\u2011month\/1\u2011year password\u2011forced maintenance shutdown. Delivered in 20 days. Read the food plant clean lifting solution.<\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-6979 case type-case status-publish has-post-thumbnail hentry product_category-turntables application_category-energy-oil application_category-new-energy application_category-testing\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/8-5ton-heavyduty-rotating-platform-for-pv-testing\/\" aria-label=\"Read More 8.5\u2011Ton Heavy\u2011Duty Rotating Platform for PV Testing | Step Accuracy \u00b10.5\u00b0 + Slip Ring\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"748\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/8.5\u2011Ton-Heavy\u2011Duty-Rotating-Platform-for-PV-Testing-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/8.5\u2011Ton-Heavy\u2011Duty-Rotating-Platform-for-PV-Testing-1.webp 1000w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/8.5\u2011Ton-Heavy\u2011Duty-Rotating-Platform-for-PV-Testing-1-300x224.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/8.5\u2011Ton-Heavy\u2011Duty-Rotating-Platform-for-PV-Testing-1-768x574.webp 768w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/8.5\u2011Ton-Heavy\u2011Duty-Rotating-Platform-for-PV-Testing-1-16x12.webp 16w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/05\/8.5\u2011Ton-Heavy\u2011Duty-Rotating-Platform-for-PV-Testing-1-600x449.webp 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/8-5ton-heavyduty-rotating-platform-for-pv-testing\/\">8.5\u2011Ton Heavy\u2011Duty Rotating Platform for PV Testing | Step Accuracy \u00b10.5\u00b0 + Slip Ring<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">RESOURCE CENTER &gt; CASE STUDIES 8.5\u2011Ton Heavy\u2011Duty Rotating Platform for PV Testing | Step Accuracy \u00b10.5\u00b0 + Slip Ring RELATED MEDIA SHARE POSTED: 5\/6\/2026 OverviewProject type: Large\u2011scale heavy\u2011duty rotating platform (turntable)Client: Xintu (Jiaxing) Digital Technology Co., Ltd.Industry: PV testing &amp; digital energyKey challenges: 8.5m diameter, 8.5\u2011ton load, step accuracy \u00b10.5\u00b0, ultra\u2011low speed (0.01\u20110.1rpm), 360\u00b0 arbitrary&#8230;<\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-6963 case type-case status-publish has-post-thumbnail hentry product_category-freight-lifts-vrc application_category-agvready application_category-battery application_category-new-energy application_category-stainless\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/lithiumdedicated-guide-rail-liftcopperfree-zincfree-stainless-steelagvready-interface\/\" aria-label=\"Read More Lithium\u2011Dedicated Guide Rail Lift\uff5cCopper\u2011Free &#038; Zinc\u2011Free Stainless Steel\uff5cAGV\u2011Ready Interface\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Lithium\u2011Dedicated-Guide-Rail-Lift\uff5cCopper\u2011Free-Zinc\u2011Free-Stainless-Steel\uff5cAGV\u2011Ready-Interface-3_watermarked.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Lithium\u2011Dedicated-Guide-Rail-Lift\uff5cCopper\u2011Free-Zinc\u2011Free-Stainless-Steel\uff5cAGV\u2011Ready-Interface-3_watermarked.webp 1000w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Lithium\u2011Dedicated-Guide-Rail-Lift\uff5cCopper\u2011Free-Zinc\u2011Free-Stainless-Steel\uff5cAGV\u2011Ready-Interface-3_watermarked-300x300.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Lithium\u2011Dedicated-Guide-Rail-Lift\uff5cCopper\u2011Free-Zinc\u2011Free-Stainless-Steel\uff5cAGV\u2011Ready-Interface-3_watermarked-150x150.webp 150w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Lithium\u2011Dedicated-Guide-Rail-Lift\uff5cCopper\u2011Free-Zinc\u2011Free-Stainless-Steel\uff5cAGV\u2011Ready-Interface-3_watermarked-768x768.webp 768w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Lithium\u2011Dedicated-Guide-Rail-Lift\uff5cCopper\u2011Free-Zinc\u2011Free-Stainless-Steel\uff5cAGV\u2011Ready-Interface-3_watermarked-12x12.webp 12w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Lithium\u2011Dedicated-Guide-Rail-Lift\uff5cCopper\u2011Free-Zinc\u2011Free-Stainless-Steel\uff5cAGV\u2011Ready-Interface-3_watermarked-600x600.webp 600w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Lithium\u2011Dedicated-Guide-Rail-Lift\uff5cCopper\u2011Free-Zinc\u2011Free-Stainless-Steel\uff5cAGV\u2011Ready-Interface-3_watermarked-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/lithiumdedicated-guide-rail-liftcopperfree-zincfree-stainless-steelagvready-interface\/\">Lithium\u2011Dedicated Guide Rail Lift\uff5cCopper\u2011Free &#038; Zinc\u2011Free Stainless Steel\uff5cAGV\u2011Ready Interface<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">1.5\u2011ton guide rail lift for Xinjiang Xihai Lithium: 304 stainless steel car, copper\u2011free &#038; zinc\u2011free design prevents contamination. 6m travel heavy\u2011duty lifting, elevator\u2011grade safety gear. Pre\u2011wired PROFINET\/Modbus TCP ports for seamless AGV integration. Ideal for ultra\u2011clean lithium material handling. <\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-6951 case type-case status-publish has-post-thumbnail hentry product_category-freight-lifts-vrc application_category-europe application_category-pitless application_category-warehousing\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/3ton-guide-rail-lift-for-spain-pitless-installation-forklift-ramp-loading\/\" aria-label=\"Read More 3\u2011Ton Guide Rail Lift for Spain\uff5cPit\u2011less Installation\uff0bForklift Ramp Loading\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/3\u2011Ton-Guide-Rail-Lift-for-Spain\uff5cPit\u2011less-Installation\uff0bForklift-Ramp-Loading.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/3\u2011Ton-Guide-Rail-Lift-for-Spain\uff5cPit\u2011less-Installation\uff0bForklift-Ramp-Loading.webp 900w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/3\u2011Ton-Guide-Rail-Lift-for-Spain\uff5cPit\u2011less-Installation\uff0bForklift-Ramp-Loading-300x300.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/3\u2011Ton-Guide-Rail-Lift-for-Spain\uff5cPit\u2011less-Installation\uff0bForklift-Ramp-Loading-150x150.webp 150w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/3\u2011Ton-Guide-Rail-Lift-for-Spain\uff5cPit\u2011less-Installation\uff0bForklift-Ramp-Loading-768x768.webp 768w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/3\u2011Ton-Guide-Rail-Lift-for-Spain\uff5cPit\u2011less-Installation\uff0bForklift-Ramp-Loading-12x12.webp 12w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/3\u2011Ton-Guide-Rail-Lift-for-Spain\uff5cPit\u2011less-Installation\uff0bForklift-Ramp-Loading-600x600.webp 600w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/3\u2011Ton-Guide-Rail-Lift-for-Spain\uff5cPit\u2011less-Installation\uff0bForklift-Ramp-Loading-100x100.webp 100w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/3ton-guide-rail-lift-for-spain-pitless-installation-forklift-ramp-loading\/\">3\u2011Ton Guide Rail Lift for Spain\uff5cPit\u2011less Installation\uff0bForklift Ramp Loading<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">3\u2011ton guide rail hydraulic lift delivered to FLUITECNIK S.A. in Spain. Pit\u2011less design, 10\u00b0 ramp for electric forklifts, roller door interlock, CE compliant, compact wooden crate shipping. Read the export case study.<\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-6919 case type-case status-publish has-post-thumbnail hentry product_category-upenders application_category-equipment-manufacturing application_category-manufacturing application_category-new-energy\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/20-ton-hydraulic-tilter-v-groove-self-centering-for-wind-tower-pressure-pipe\/\" aria-label=\"Read More 20-Ton Hydraulic Tilter | V-Groove Self-Centering | for Wind Tower &amp; Pressure Pipe\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"749\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/20-Ton-Hydraulic-Tilter-for-Wind-Tower-Pressure-Pipe-01.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/20-Ton-Hydraulic-Tilter-for-Wind-Tower-Pressure-Pipe-01.webp 1000w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/20-Ton-Hydraulic-Tilter-for-Wind-Tower-Pressure-Pipe-01-300x225.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/20-Ton-Hydraulic-Tilter-for-Wind-Tower-Pressure-Pipe-01-768x575.webp 768w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/20-Ton-Hydraulic-Tilter-for-Wind-Tower-Pressure-Pipe-01-16x12.webp 16w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/20-Ton-Hydraulic-Tilter-for-Wind-Tower-Pressure-Pipe-01-600x449.webp 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/20-ton-hydraulic-tilter-v-groove-self-centering-for-wind-tower-pressure-pipe\/\">20-Ton Hydraulic Tilter | V-Groove Self-Centering | for Wind Tower &amp; Pressure Pipe<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">20-ton heavy-duty hydraulic tilter for 90\u00b0 turnover of wind tower sections and pressure pipes. V-groove fits workpieces 2.5-7m diameter. L-shaped twin platforms, heavy-wall rectangular frame, smooth 10-minute tilting. Proven at a PowerChina new energy base.<\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-6909 case type-case status-publish has-post-thumbnail hentry product_category-scissor-lift-tables application_category-entertainment application_category-stage application_category-underwater\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/underwater-lifting-rotating-stage-3-independent-rings-dmx512-control\/\" aria-label=\"Read More Underwater Lifting &#038; Rotating Stage | 3 Independent Rings + DMX512 Control\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/DJI_20260422073140_0018_D_watermarked.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/DJI_20260422073140_0018_D_watermarked.webp 1000w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/DJI_20260422073140_0018_D_watermarked-300x300.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/DJI_20260422073140_0018_D_watermarked-150x150.webp 150w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/DJI_20260422073140_0018_D_watermarked-768x768.webp 768w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/DJI_20260422073140_0018_D_watermarked-12x12.webp 12w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/DJI_20260422073140_0018_D_watermarked-600x600.webp 600w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/DJI_20260422073140_0018_D_watermarked-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/underwater-lifting-rotating-stage-3-independent-rings-dmx512-control\/\">Underwater Lifting &#038; Rotating Stage | 3 Independent Rings + DMX512 Control<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Custom underwater lifting &#038; rotating stage for Suzhou Siyan Culture. Three independent rings, scissor mechanism drive, hot-dip galvanized, water-glycol fluid, DMX512 control. Seamless sync with lighting &#038; fountain shows. 14\u2011day urgent delivery. Read the case study.<\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-6894 case type-case status-publish has-post-thumbnail hentry product_category-freight-lifts-vrc application_category-food-pharmaceutical\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/reciprocating-lift-case-study-food-industry-bagged-material-lift\/\" aria-label=\"Read More Reciprocating Lift Case Study | Food Industry Bagged Material Lift\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"749\" height=\"1000\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Reciprocating-Lift-Case-Study-Food-Industry-Bagged-Material-Lift-01.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Reciprocating-Lift-Case-Study-Food-Industry-Bagged-Material-Lift-01.webp 749w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Reciprocating-Lift-Case-Study-Food-Industry-Bagged-Material-Lift-01-225x300.webp 225w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Reciprocating-Lift-Case-Study-Food-Industry-Bagged-Material-Lift-01-9x12.webp 9w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Reciprocating-Lift-Case-Study-Food-Industry-Bagged-Material-Lift-01-600x801.webp 600w\" sizes=\"(max-width: 749px) 100vw, 749px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/reciprocating-lift-case-study-food-industry-bagged-material-lift\/\">Reciprocating Lift Case Study | Food Industry Bagged Material Lift<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Defuxiang Food\u2019s 2500kg custom reciprocating lift solves 17.5m travel and bagged material spillage. Includes a 9.67m horizontal connecting conveyor for seamless \u201chorizontal\u2011vertical\u2011horizontal\u201d automation. Zero spillage, high safety. Read the full case study.<\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-6887 case type-case status-publish has-post-thumbnail hentry product_category-freight-lifts-vrc application_category-construction\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/reciprocating-lift-case-study-pit-less-through-floor-installation-for-factory-renovation\/\" aria-label=\"Read More Reciprocating Lift Case Study | Pit-less Through-Floor Installation for Factory Renovation\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"836\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Reciprocating-Lift-Case-Study-Pit-less-Through-Floor-Installation-for-Factory-Renovation-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Reciprocating-Lift-Case-Study-Pit-less-Through-Floor-Installation-for-Factory-Renovation-1.webp 727w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Reciprocating-Lift-Case-Study-Pit-less-Through-Floor-Installation-for-Factory-Renovation-1-261x300.webp 261w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Reciprocating-Lift-Case-Study-Pit-less-Through-Floor-Installation-for-Factory-Renovation-1-10x12.webp 10w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Reciprocating-Lift-Case-Study-Pit-less-Through-Floor-Installation-for-Factory-Renovation-1-600x690.webp 600w\" sizes=\"(max-width: 727px) 100vw, 727px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/reciprocating-lift-case-study-pit-less-through-floor-installation-for-factory-renovation\/\">Reciprocating Lift Case Study | Pit-less Through-Floor Installation for Factory Renovation<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Factory renovation project for Suzhou Liliang \u2013 2 custom reciprocating lifts. Floor slab opened, basement floor anchoring with 4.65m extended columns (pit-less through-floor design). 3 stops, C-shaped access (1600mm direction), 500kg capacity, 16.4m travel. 9.2kW SEW motor with VFD + dual safety gears. Delivered in 28 days. Read the full case study.<\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-6827 case type-case status-publish has-post-thumbnail hentry product_category-freight-lifts-vrc application_category-defense-government\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/guide-rail-lift-pit-less-ramp-loading-museum-grade-finish\/\" aria-label=\"Read More Guide Rail Lift | Pit-less Ramp Loading | Museum-grade Finish\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"999\" height=\"670\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Guide-Rail-Lift-Pit-less-Ramp-Loading-Museum-grade-Finish.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Guide-Rail-Lift-Pit-less-Ramp-Loading-Museum-grade-Finish.webp 999w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Guide-Rail-Lift-Pit-less-Ramp-Loading-Museum-grade-Finish-300x201.webp 300w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Guide-Rail-Lift-Pit-less-Ramp-Loading-Museum-grade-Finish-768x515.webp 768w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Guide-Rail-Lift-Pit-less-Ramp-Loading-Museum-grade-Finish-18x12.webp 18w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2026\/04\/Guide-Rail-Lift-Pit-less-Ramp-Loading-Museum-grade-Finish-600x402.webp 600w\" sizes=\"(max-width: 999px) 100vw, 999px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/www.gradinlifts.com\/ko\/case\/guide-rail-lift-pit-less-ramp-loading-museum-grade-finish\/\">Guide Rail Lift | Pit-less Ramp Loading | Museum-grade Finish<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Custom guide rail hydraulic lift for Hongrui Wenbo Group: 600kg capacity, pit-less through-type design, ground-level ramp loading, top hard stop anti-over-travel, RAL7035 premium painting. Ideal for museums, archives, and high-finish applications. Read the full case study.<\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>G-V11 \uad74\uc808\uc2dd \ubd90 \ub9ac\ud504\ud2b8\ub294 \ub0ae\uc740 \ub192\uc774\uc758 \uace0\uc18c \uc791\uc5c5 \uc694\uac74\uc5d0 \uc801\ud569\ud55c \uc778\uae30 \uc81c\ud488\uc785\ub2c8\ub2e4. \ucd5c\ub300 \uc791\uc5c5 \ub192\uc774\uac00 12.52\ubbf8\ud130\uc5d0 \ub2ec\ud558\ub294 \uc774 \uc81c\ud488\uc740 \uac74\uc124, \uc7a5\uc2dd, \ud1b5\uc2e0, \uad11\uace0\ubb3c \uc124\uce58, \uacf5\ud56d \uc720\uc9c0\ubcf4\uc218 \ub4f1 \ub2e4\uc591\ud55c \ubd84\uc57c\uc5d0 \uc774\uc0c1\uc801\uc785\ub2c8\ub2e4. \uc544\ub798 \uc0ac\uc591\uc744 \uc0b4\ud3b4\ubcf4\uace0 \uc774 \uc791\uc9c0\ub9cc \uac15\ub825\ud55c \uad74\uc808\uc2dd \ubd90 \ub9ac\ud504\ud2b8\uc758 \uace0\uc720\ud55c \ud2b9\uc9d5\uacfc \uc774\uc810\uc744 \uc54c\uc544\ubcf4\uc138\uc694.<\/p>","protected":false},"featured_media":5112,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"product_category":[177],"application_category":[],"product_cat":[199],"product_tag":[200,130,80,173,77,86],"class_list":{"0":"post-6012","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_category-boom-lifts","7":"product_cat-boom-lift","8":"product_tag-boom-lift","9":"product_tag-electric-control","10":"product_tag-hydraulic","11":"product_tag-mobile","12":"product_tag-self-propelled","13":"product_tag-with-wheels","14":"pa_lift-capacity-less-than-1ton","16":"first","17":"instock","18":"shipping-taxable","19":"product-type-simple","20":"entry","21":"content-bg","22":"loop-entry"},"acf":[],"taxonomy_info":{"product_category":[{"value":177,"label":"Boom Lifts"}],"product_cat":[{"value":199,"label":"Boom Lift"}],"product_tag":[{"value":200,"label":"Boom Lift"},{"value":130,"label":"Electric Control"},{"value":80,"label":"Hydraulic"},{"value":173,"label":"Mobile"},{"value":77,"label":"Self Propelled"},{"value":86,"label":"With Wheels"}],"pa_lift-capacity":[{"value":30,"label":"\u2264 1 ton"}]},"featured_image_src_large":["https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/10\/2024071249.webp",460,330,false],"author_info":[],"comment_info":0,"_links":{"self":[{"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/product\/6012"}],"collection":[{"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/comments?post=6012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/media\/5112"}],"wp:attachment":[{"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/media?parent=6012"}],"wp:term":[{"taxonomy":"product_category","embeddable":true,"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/product_category?post=6012"},{"taxonomy":"application_category","embeddable":true,"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/application_category?post=6012"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/product_cat?post=6012"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/product_tag?post=6012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}