{"id":4462,"date":"2024-08-30T16:05:36","date_gmt":"2024-08-30T08:05:36","guid":{"rendered":"https:\/\/www.gradinlifts.com\/?post_type=product&#038;p=4462"},"modified":"2025-01-26T15:31:24","modified_gmt":"2025-01-26T07:31:24","slug":"stationary-scissor-dock-lift","status":"publish","type":"product","link":"https:\/\/www.gradinlifts.com\/ko\/product\/stationary-scissor-dock-lift\/","title":{"rendered":"\uace0\uc815\uc2dd \uc2dc\uc800\uc2a4 \ub3c4\ud06c \ub9ac\ud504\ud2b8"},"content":{"rendered":"<style>.kb-row-layout-id4462_a63c4f-20 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4462_a63c4f-20 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4462_a63c4f-20 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4462_a63c4f-20{background-color:#ebeef2;}.kb-row-layout-id4462_a63c4f-20 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4462_a63c4f-20 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4462_a63c4f-20 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4462_a63c4f-20 alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4462_b9d819-5b > .kt-inside-inner-col{padding-right:12rem;padding-bottom:3rem;padding-left:12rem;}.kadence-column4462_b9d819-5b > .kt-inside-inner-col,.kadence-column4462_b9d819-5b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_b9d819-5b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_b9d819-5b > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_b9d819-5b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_b9d819-5b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_b9d819-5b{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_b9d819-5b > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_b9d819-5b > .kt-inside-inner-col{padding-right:0rem;padding-bottom:2rem;padding-left:0rem;flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_b9d819-5b\"><div class=\"kt-inside-inner-col\"><style>.kt-tabs-id4462_74d08a-3e > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:1px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid var(u002du002dglobal-palette7, #eeeeee);border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:0px;background:#ebeef2;}.wp-block-kadence-tabs .kt-tabs-id4462_74d08a-3e > .kt-tabs-title-list li{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id4462_74d08a-3e > .kt-tabs-title-list li:last-child{margin-right:0px;}.wp-block-kadence-tabs .kt-tabs-id4462_74d08a-3e > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id4462_74d08a-3e > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{line-height:1.4em;font-weight:regular;font-style:normal;border-top-width:0px;border-right-width:0px;border-bottom-width:4px;border-left-width:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:1rem;padding-right:2rem;padding-bottom:1rem;padding-left:2rem;border-color:var(u002du002dglobal-palette9, #ffffff);color:var(u002du002dglobal-palette5, #444444);background:var(u002du002dglobal-palette9, #ffffff);}.wp-block-kadence-tabs .kt-tabs-id4462_74d08a-3e > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id4462_74d08a-3e > .kt-tabs-title-list li .kt-tab-title:hover, .wp-block-kadence-tabs .kt-tabs-id4462_74d08a-3e > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title:hover{border-color:var(u002du002dglobal-palette7, #eeeeee);color:var(u002du002dglobal-palette5, #444444);background:var(u002du002dglobal-palette9, #ffffff);}.wp-block-kadence-tabs .kt-tabs-id4462_74d08a-3e > .kt-tabs-title-list li.kt-tab-title-active .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id4462_74d08a-3e > .kt-tabs-content-wrap > .kt-tabs-accordion-title.kt-tab-title-active .kt-tab-title{border-color:#0a6689;color:#0a6689;background:var(u002du002dglobal-palette9, #ffffff);}@media all and (max-width: 1024px){.kt-tabs-id4462_74d08a-3e > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:1px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid var(u002du002dglobal-palette7, #eeeeee);border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-tabs-id4462_74d08a-3e > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:1px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid var(u002du002dglobal-palette7, #eeeeee);border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-tabs alignnone product-detail-tab\"><div class=\"kt-tabs-wrap kt-tabs-id4462_74d08a-3e kt-tabs-has-5-tabs kt-active-tab-1 kt-tabs-layout-tabs kt-tabs-tablet-layout-inherit kt-tabs-mobile-layout-tabs kt-tab-alignment-center \"><ul class=\"kt-tabs-title-list\"><li id=\"tab-modelsampspecs\" class=\"kt-title-item kt-title-item-1 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-active\"><a href=\"#tab-modelsampspecs\" data-tab=\"1\" class=\"kt-tab-title kt-tab-title-1 \"><span class=\"kt-title-text\">Models &amp; Specs<\/span><\/a><\/li><li id=\"tab-customoptions\" class=\"kt-title-item kt-title-item-2 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-customoptions\" data-tab=\"2\" class=\"kt-tab-title kt-tab-title-2 \"><span class=\"kt-title-text\">Custom Options<\/span><\/a><\/li><li id=\"tab-structureampfeatures\" class=\"kt-title-item kt-title-item-3 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-structureampfeatures\" data-tab=\"3\" class=\"kt-tab-title kt-tab-title-3 \"><span class=\"kt-title-text\">Structure &amp; Features<\/span><\/a><\/li><li id=\"tab-casestudiesampvideos\" class=\"kt-title-item kt-title-item-4 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-casestudiesampvideos\" data-tab=\"4\" class=\"kt-tab-title kt-tab-title-4 \"><span class=\"kt-title-text\">Case Studies &amp; Videos<\/span><\/a><\/li><li id=\"tab-productdocuments\" class=\"kt-title-item kt-title-item-5 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-productdocuments\" data-tab=\"5\" class=\"kt-tab-title kt-tab-title-5 \"><span class=\"kt-title-text\">Product Documents<\/span><\/a><\/li><\/ul><div class=\"kt-tabs-content-wrap\"><div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-1 kt-inner-tab_96458e-d9\"><div class=\"kt-tab-inner-content-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4462_4138eb-6e, .wp-block-kadence-advancedheading.kt-adv-heading4462_4138eb-6e[data-kb-block=\"kb-adv-heading4462_4138eb-6e\"]{display:block;margin-top:var(--global-kb-spacing-sm, 1.5rem);font-size:1.5rem;font-style:normal;color:#949aa3;}.wp-block-kadence-advancedheading.kt-adv-heading4462_4138eb-6e mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_4138eb-6e[data-kb-block=\"kb-adv-heading4462_4138eb-6e\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading4462_4138eb-6e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_4138eb-6e\"><strong>Stationary Scissor Dock Lift<\/strong><div class=\"elementor-element elementor-element-13bdd58 elementor-widget elementor-widget-text-editor\" data-id=\"13bdd58\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\" style=\"box-sizing: border-box; --flex-direction: initial; --flex-wrap: initial; --justify-content: initial; --align-items: initial; --align-content: initial; --gap: initial; --flex-basis: initial; --flex-grow: initial; --flex-shrink: initial; --order: initial; --align-self: initial; flex-basis: var(--flex-basis); flex-grow: var(--flex-grow); flex-shrink: var(--flex-shrink); order: var(--order); align-self: var(--align-self); flex-direction: var(--flex-direction); flex-wrap: var(--flex-wrap); justify-content: var(--justify-content); align-items: var(--align-items); align-content: var(--align-content); gap: var(--gap); position: relative; --swiper-theme-color: #000; --swiper-navigation-size: 44px; --swiper-pagination-bullet-size: 6px; --swiper-pagination-bullet-horizontal-gap: 6px; --widgets-spacing: 10px 10px; color: rgb(85, 85, 85); font-family: Roboto, sans-serif; transition: 0.3s linear; width: 610px; margin-block-end: 10px; margin-bottom: 0px; text-align: justify; font-size: 18px; line-height: 30px; white-space-collapse: collapse; background-color: rgb(255, 255, 255);\"><div class=\"elementor-widget-container\" style=\"box-sizing: border-box; transition: background .3s,border .3s,border-radius .3s,box-shadow .3s,transform var(--e-transform-transition-duration,.4s);\"><\/div><div class=\"elementor-widget-container\" style=\"box-sizing: border-box; transition: background .3s,border .3s,border-radius .3s,box-shadow .3s,transform var(--e-transform-transition-duration,.4s);\"><\/div><div class=\"elementor-widget-container\" style=\"box-sizing: border-box; transition: background .3s,border .3s,border-radius .3s,box-shadow .3s,transform var(--e-transform-transition-duration,.4s);\"><\/div><\/div><\/span>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4462_fd6bbe-e5, .wp-block-kadence-advancedheading.kt-adv-heading4462_fd6bbe-e5[data-kb-block=\"kb-adv-heading4462_fd6bbe-e5\"]{padding-bottom:0px;margin-top:1rem;margin-bottom:3rem;font-size:4rem;line-height:1;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading4462_fd6bbe-e5 mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_fd6bbe-e5[data-kb-block=\"kb-adv-heading4462_fd6bbe-e5\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4462_fd6bbe-e5, .wp-block-kadence-advancedheading.kt-adv-heading4462_fd6bbe-e5[data-kb-block=\"kb-adv-heading4462_fd6bbe-e5\"]{font-size:2.3rem;}}<\/style>\n<h2 class=\"kt-adv-heading4462_fd6bbe-e5 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_fd6bbe-e5\">Models &amp; Specs<\/h2>\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td>Feature<\/td><td>Explosion-Proof, Insulating<\/td><\/tr><tr><td>Certification<\/td><td>CE, ISO 9001<\/td><\/tr><tr><td>Platform Height<\/td><td>2m<\/td><\/tr><tr><td>Load Capcity<\/td><td>20000kg<\/td><\/tr><tr><td>Supply Voltage<\/td><td>220\/380V<\/td><\/tr><tr><td>Weight<\/td><td>2000kg<\/td><\/tr><tr><td>Design<\/td><td>Scissor<\/td><\/tr><tr><td>Packaging<\/td><td>Wooden Packaging or Nude<\/td><\/tr><tr><td>Color<\/td><td>as You Demand<\/td><\/tr><tr><td>Warranty<\/td><td>One Year<\/td><\/tr><tr><td>Lift Drive<\/td><td>Hydraulic<\/td><\/tr><tr><td>Pit<\/td><td>100-200mm Pit<\/td><\/tr><tr><td>Material<\/td><td>High-Duty Steel Structure<\/td><\/tr><tr><td>Platform<\/td><td>Anti-Skid Checkered Plate<\/td><\/tr><tr><td>Condition<\/td><td>New<\/td><\/tr><tr><td>Table Size<\/td><td>According to Demand<\/td><\/tr><tr><td>Emergency Lowing Valve<\/td><td>Included<\/td><\/tr><tr><td>Transport Package<\/td><td>Sea, Air and Land Transport<\/td><\/tr><tr><td>Specification<\/td><td>1600*1300<\/td><\/tr><tr><td>Origin<\/td><td>Shandong China<\/td><\/tr><tr><td>Production Capacity<\/td><td>12000pieces\/Year<\/td><\/tr><\/tbody><\/table><\/figure><\/div><\/div>\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-2 kt-inner-tab_e68ef5-df\"><div class=\"kt-tab-inner-content-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4462_9da66a-c4, .wp-block-kadence-advancedheading.kt-adv-heading4462_9da66a-c4[data-kb-block=\"kb-adv-heading4462_9da66a-c4\"]{display:block;margin-top:var(--global-kb-spacing-sm, 1.5rem);font-size:1.5rem;font-style:normal;color:#949aa3;}.wp-block-kadence-advancedheading.kt-adv-heading4462_9da66a-c4 mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_9da66a-c4[data-kb-block=\"kb-adv-heading4462_9da66a-c4\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading4462_9da66a-c4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_9da66a-c4\"><strong>Stationary Scissor Dock Lift<\/strong><div class=\"elementor-element elementor-element-13bdd58 elementor-widget elementor-widget-text-editor\" data-id=\"13bdd58\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\" style=\"box-sizing: border-box; --flex-direction: initial; --flex-wrap: initial; --justify-content: initial; --align-items: initial; --align-content: initial; --gap: initial; --flex-basis: initial; --flex-grow: initial; --flex-shrink: initial; --order: initial; --align-self: initial; flex-basis: var(--flex-basis); flex-grow: var(--flex-grow); flex-shrink: var(--flex-shrink); order: var(--order); align-self: var(--align-self); flex-direction: var(--flex-direction); flex-wrap: var(--flex-wrap); justify-content: var(--justify-content); align-items: var(--align-items); align-content: var(--align-content); gap: var(--gap); position: relative; --swiper-theme-color: #000; --swiper-navigation-size: 44px; --swiper-pagination-bullet-size: 6px; --swiper-pagination-bullet-horizontal-gap: 6px; --widgets-spacing: 10px 10px; color: rgb(85, 85, 85); font-family: Roboto, sans-serif; transition: 0.3s linear; width: 610px; margin-block-end: 10px; margin-bottom: 0px; text-align: justify; font-size: 18px; line-height: 30px; white-space-collapse: collapse; background-color: rgb(255, 255, 255);\"><div class=\"elementor-widget-container\" style=\"box-sizing: border-box; transition: background .3s,border .3s,border-radius .3s,box-shadow .3s,transform var(--e-transform-transition-duration,.4s);\"><\/div><div class=\"elementor-widget-container\" style=\"box-sizing: border-box; transition: background .3s,border .3s,border-radius .3s,box-shadow .3s,transform var(--e-transform-transition-duration,.4s);\"><\/div><div class=\"elementor-widget-container\" style=\"box-sizing: border-box; transition: background .3s,border .3s,border-radius .3s,box-shadow .3s,transform var(--e-transform-transition-duration,.4s);\"><\/div><\/div><\/span>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4462_7bb5f7-62, .wp-block-kadence-advancedheading.kt-adv-heading4462_7bb5f7-62[data-kb-block=\"kb-adv-heading4462_7bb5f7-62\"]{padding-bottom:0px;margin-top:var(--global-kb-spacing-xs, 1rem);font-size:4rem;line-height:1;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading4462_7bb5f7-62 mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_7bb5f7-62[data-kb-block=\"kb-adv-heading4462_7bb5f7-62\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading4462_7bb5f7-62 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_7bb5f7-62\">Custom Options<\/h2>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4462_7eb589-7b, .wp-block-kadence-advancedheading.kt-adv-heading4462_7eb589-7b[data-kb-block=\"kb-adv-heading4462_7eb589-7b\"]{margin-top:2rem;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading4462_7eb589-7b mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_7eb589-7b[data-kb-block=\"kb-adv-heading4462_7eb589-7b\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading4462_7eb589-7b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_7eb589-7b\"><strong>Customize Your Lifts<\/strong><\/p>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4462_3b995f-e0, .wp-block-kadence-advancedheading.kt-adv-heading4462_3b995f-e0[data-kb-block=\"kb-adv-heading4462_3b995f-e0\"]{margin-bottom:2rem;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading4462_3b995f-e0 mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_3b995f-e0[data-kb-block=\"kb-adv-heading4462_3b995f-e0\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading4462_3b995f-e0 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_3b995f-e0\">Specifically sized, configured, mobile, high-cycle, or automated &#8211; when you need a lift to perform a specific function, we have the materials, components, and design techniques to produce a one-of-a-kind lifting solution for your application.<\/p>\n\n<style>.kb-row-layout-id1399_f77cfe-72 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1399_f77cfe-72 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1399_f77cfe-72 > .kt-row-column-wrap{column-gap:0.5rem;row-gap:0.5rem;padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);padding-left:var(--global-kb-spacing-md, 2rem);grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id1399_f77cfe-72 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1399_f77cfe-72 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1399_f77cfe-72 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1399_f77cfe-72 alignnone custom-list wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1399_91757f-e4 > .kt-inside-inner-col{display:flex;}.kadence-column1399_91757f-e4 > .kt-inside-inner-col,.kadence-column1399_91757f-e4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_91757f-e4 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-md, 2rem);column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_91757f-e4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_91757f-e4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_91757f-e4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_91757f-e4{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_91757f-e4 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_91757f-e4 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_91757f-e4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_47b624-ff, .wp-block-kadence-advancedheading.kt-adv-heading1399_47b624-ff[data-kb-block=\"kb-adv-heading1399_47b624-ff\"]{margin-top:0px;text-align:left;font-style:normal;text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading1399_47b624-ff mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_47b624-ff[data-kb-block=\"kb-adv-heading1399_47b624-ff\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<div class=\"kt-adv-heading1399_47b624-ff wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_47b624-ff\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/controls\/\" data-type=\"design-options\" data-id=\"1251\" rel=\"nofollow\">controls<\/a><\/div><\/div><\/div>\n\n<style>.kadence-column1399_469127-dc > .kt-inside-inner-col,.kadence-column1399_469127-dc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_469127-dc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_469127-dc > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_469127-dc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_469127-dc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_469127-dc{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_469127-dc > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_469127-dc > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_469127-dc\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_f8ad1c-e7, .wp-block-kadence-advancedheading.kt-adv-heading1399_f8ad1c-e7[data-kb-block=\"kb-adv-heading1399_f8ad1c-e7\"]{margin-top:0px;text-align:left;font-style:normal;text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading1399_f8ad1c-e7 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_f8ad1c-e7[data-kb-block=\"kb-adv-heading1399_f8ad1c-e7\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<div class=\"kt-adv-heading1399_f8ad1c-e7 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_f8ad1c-e7\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/safety\/\" data-type=\"design-options\" data-id=\"1248\" rel=\"nofollow\">Safety<\/a><\/div><\/div><\/div>\n\n<style>.kadence-column1399_cca2dd-d9 > .kt-inside-inner-col,.kadence-column1399_cca2dd-d9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_cca2dd-d9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_cca2dd-d9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_cca2dd-d9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_cca2dd-d9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_cca2dd-d9{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_cca2dd-d9 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_cca2dd-d9 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_cca2dd-d9\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_16b45a-92, .wp-block-kadence-advancedheading.kt-adv-heading1399_16b45a-92[data-kb-block=\"kb-adv-heading1399_16b45a-92\"]{display:block;margin-top:0px;text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_16b45a-92 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_16b45a-92[data-kb-block=\"kb-adv-heading1399_16b45a-92\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_16b45a-92 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_16b45a-92\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/mobility\/\" data-type=\"design-options\" data-id=\"1250\" rel=\"nofollow\">Mobility<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_624850-62 > .kt-inside-inner-col,.kadence-column1399_624850-62 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_624850-62 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_624850-62 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_624850-62 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_624850-62 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_624850-62{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_624850-62 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_624850-62 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_624850-62\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_c8b213-1d, .wp-block-kadence-advancedheading.kt-adv-heading1399_c8b213-1d[data-kb-block=\"kb-adv-heading1399_c8b213-1d\"]{display:block;margin-top:0px;text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_c8b213-1d mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_c8b213-1d[data-kb-block=\"kb-adv-heading1399_c8b213-1d\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_c8b213-1d wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_c8b213-1d\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/platform-configurations\/\" data-type=\"design-options\" data-id=\"1253\" rel=\"nofollow\">Platform Configurations<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_559f6b-8e > .kt-inside-inner-col,.kadence-column1399_559f6b-8e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_559f6b-8e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_559f6b-8e > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_559f6b-8e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_559f6b-8e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_559f6b-8e{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_559f6b-8e > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_559f6b-8e > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_559f6b-8e\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_e587ca-a2, .wp-block-kadence-advancedheading.kt-adv-heading1399_e587ca-a2[data-kb-block=\"kb-adv-heading1399_e587ca-a2\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_e587ca-a2 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_e587ca-a2[data-kb-block=\"kb-adv-heading1399_e587ca-a2\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_e587ca-a2 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_e587ca-a2\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/platform-shuttle\/\" data-type=\"design-options\" data-id=\"1254\" rel=\"nofollow\">Platform Shuttle<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_80f33a-0a > .kt-inside-inner-col,.kadence-column1399_80f33a-0a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_80f33a-0a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_80f33a-0a > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_80f33a-0a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_80f33a-0a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_80f33a-0a{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_80f33a-0a > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_80f33a-0a > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_80f33a-0a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_65206b-69, .wp-block-kadence-advancedheading.kt-adv-heading1399_65206b-69[data-kb-block=\"kb-adv-heading1399_65206b-69\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading1399_65206b-69 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_65206b-69[data-kb-block=\"kb-adv-heading1399_65206b-69\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_65206b-69 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_65206b-69\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/tilt\/\" data-type=\"design-options\" data-id=\"1255\" rel=\"nofollow\">Tilt<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_887e6b-6d > .kt-inside-inner-col,.kadence-column1399_887e6b-6d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_887e6b-6d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_887e6b-6d > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_887e6b-6d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_887e6b-6d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_887e6b-6d{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_887e6b-6d > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_887e6b-6d > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_887e6b-6d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_f2f2c1-7d, .wp-block-kadence-advancedheading.kt-adv-heading1399_f2f2c1-7d[data-kb-block=\"kb-adv-heading1399_f2f2c1-7d\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_f2f2c1-7d mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_f2f2c1-7d[data-kb-block=\"kb-adv-heading1399_f2f2c1-7d\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_f2f2c1-7d wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_f2f2c1-7d\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/turn-rotate\/\" data-type=\"design-options\" data-id=\"1256\" rel=\"nofollow\">Turn &amp; Rotate<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_9cefde-3e > .kt-inside-inner-col,.kadence-column1399_9cefde-3e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_9cefde-3e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_9cefde-3e > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_9cefde-3e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_9cefde-3e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_9cefde-3e{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_9cefde-3e > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_9cefde-3e > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_9cefde-3e\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_928ab4-55, .wp-block-kadence-advancedheading.kt-adv-heading1399_928ab4-55[data-kb-block=\"kb-adv-heading1399_928ab4-55\"]{display:block;margin-top:0px;text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_928ab4-55 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_928ab4-55[data-kb-block=\"kb-adv-heading1399_928ab4-55\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_928ab4-55 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_928ab4-55\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/conveyors\/\" data-type=\"design-options\" data-id=\"1257\" rel=\"nofollow\">Conveyors<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_09e0e5-f1 > .kt-inside-inner-col,.kadence-column1399_09e0e5-f1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_09e0e5-f1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_09e0e5-f1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_09e0e5-f1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_09e0e5-f1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_09e0e5-f1{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_09e0e5-f1 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_09e0e5-f1 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_09e0e5-f1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_793b51-c9, .wp-block-kadence-advancedheading.kt-adv-heading1399_793b51-c9[data-kb-block=\"kb-adv-heading1399_793b51-c9\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_793b51-c9 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_793b51-c9[data-kb-block=\"kb-adv-heading1399_793b51-c9\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_793b51-c9 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_793b51-c9\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/high-travel\/\" data-type=\"design-options\" data-id=\"1258\" rel=\"nofollow\">High Travel<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_bebf5f-e4 > .kt-inside-inner-col,.kadence-column1399_bebf5f-e4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_bebf5f-e4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_bebf5f-e4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_bebf5f-e4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_bebf5f-e4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_bebf5f-e4{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_bebf5f-e4 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_bebf5f-e4 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_bebf5f-e4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_c107d0-e9, .wp-block-kadence-advancedheading.kt-adv-heading1399_c107d0-e9[data-kb-block=\"kb-adv-heading1399_c107d0-e9\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading1399_c107d0-e9 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_c107d0-e9[data-kb-block=\"kb-adv-heading1399_c107d0-e9\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_c107d0-e9 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_c107d0-e9\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/high-capacity\/\" data-type=\"design-options\" data-id=\"1259\" rel=\"nofollow\">High Capacity<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_d033e7-2b > .kt-inside-inner-col,.kadence-column1399_d033e7-2b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_d033e7-2b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_d033e7-2b > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_d033e7-2b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_d033e7-2b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_d033e7-2b{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_d033e7-2b > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_d033e7-2b > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_d033e7-2b\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_4094d0-c9, .wp-block-kadence-advancedheading.kt-adv-heading1399_4094d0-c9[data-kb-block=\"kb-adv-heading1399_4094d0-c9\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_4094d0-c9 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_4094d0-c9[data-kb-block=\"kb-adv-heading1399_4094d0-c9\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_4094d0-c9 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_4094d0-c9\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/automation\/\" data-type=\"design-options\" data-id=\"1260\" rel=\"nofollow\">Automation<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_2a63f8-3f > .kt-inside-inner-col,.kadence-column1399_2a63f8-3f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_2a63f8-3f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_2a63f8-3f > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_2a63f8-3f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_2a63f8-3f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_2a63f8-3f{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_2a63f8-3f > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_2a63f8-3f > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_2a63f8-3f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_4ca036-02, .wp-block-kadence-advancedheading.kt-adv-heading1399_4ca036-02[data-kb-block=\"kb-adv-heading1399_4ca036-02\"]{display:block;margin-top:0px;text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_4ca036-02 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_4ca036-02[data-kb-block=\"kb-adv-heading1399_4ca036-02\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_4ca036-02 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_4ca036-02\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/actuation\/\" data-type=\"design-options\" data-id=\"1261\" rel=\"nofollow\">Actuation<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_8654a1-35 > .kt-inside-inner-col,.kadence-column1399_8654a1-35 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_8654a1-35 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_8654a1-35 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_8654a1-35 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_8654a1-35 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_8654a1-35{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_8654a1-35 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_8654a1-35 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_8654a1-35\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_6a5600-9c, .wp-block-kadence-advancedheading.kt-adv-heading1399_6a5600-9c[data-kb-block=\"kb-adv-heading1399_6a5600-9c\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_6a5600-9c mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_6a5600-9c[data-kb-block=\"kb-adv-heading1399_6a5600-9c\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_6a5600-9c wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_6a5600-9c\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/lift-deflection\/\" data-type=\"design-options\" data-id=\"1262\" rel=\"nofollow\">Lift Deflection<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_4e6f8d-6e > .kt-inside-inner-col,.kadence-column1399_4e6f8d-6e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_4e6f8d-6e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_4e6f8d-6e > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_4e6f8d-6e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_4e6f8d-6e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_4e6f8d-6e{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_4e6f8d-6e > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_4e6f8d-6e > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_4e6f8d-6e\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_e64250-d2, .wp-block-kadence-advancedheading.kt-adv-heading1399_e64250-d2[data-kb-block=\"kb-adv-heading1399_e64250-d2\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading1399_e64250-d2 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_e64250-d2[data-kb-block=\"kb-adv-heading1399_e64250-d2\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_e64250-d2 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_e64250-d2\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/speed\/\" data-type=\"design-options\" data-id=\"1263\" rel=\"nofollow\">Speed<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_89c9bd-2d > .kt-inside-inner-col,.kadence-column1399_89c9bd-2d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_89c9bd-2d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_89c9bd-2d > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_89c9bd-2d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_89c9bd-2d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_89c9bd-2d{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_89c9bd-2d > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_89c9bd-2d > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_89c9bd-2d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_61cd62-6f, .wp-block-kadence-advancedheading.kt-adv-heading1399_61cd62-6f[data-kb-block=\"kb-adv-heading1399_61cd62-6f\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_61cd62-6f mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_61cd62-6f[data-kb-block=\"kb-adv-heading1399_61cd62-6f\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_61cd62-6f wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_61cd62-6f\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/indexing\/\" data-type=\"design-options\" data-id=\"1264\" rel=\"nofollow\">Indexing<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_312355-57 > .kt-inside-inner-col,.kadence-column1399_312355-57 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_312355-57 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_312355-57 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_312355-57 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_312355-57 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_312355-57{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_312355-57 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_312355-57 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_312355-57\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_0136e9-03, .wp-block-kadence-advancedheading.kt-adv-heading1399_0136e9-03[data-kb-block=\"kb-adv-heading1399_0136e9-03\"]{display:block;margin-top:0px;text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_0136e9-03 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_0136e9-03[data-kb-block=\"kb-adv-heading1399_0136e9-03\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_0136e9-03 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_0136e9-03\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/locking-pins-devices\/\" data-type=\"design-options\" data-id=\"1265\" rel=\"nofollow\">Locking Pins &amp; Devices<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_9cc590-14 > .kt-inside-inner-col,.kadence-column1399_9cc590-14 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_9cc590-14 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_9cc590-14 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_9cc590-14 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_9cc590-14 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_9cc590-14{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_9cc590-14 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_9cc590-14 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_9cc590-14\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_2e58e3-3d, .wp-block-kadence-advancedheading.kt-adv-heading1399_2e58e3-3d[data-kb-block=\"kb-adv-heading1399_2e58e3-3d\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_2e58e3-3d mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_2e58e3-3d[data-kb-block=\"kb-adv-heading1399_2e58e3-3d\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_2e58e3-3d wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_2e58e3-3d\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/power-units\/\" data-type=\"design-options\" data-id=\"1266\" rel=\"nofollow\">Power Units<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_b0d1ce-84 > .kt-inside-inner-col,.kadence-column1399_b0d1ce-84 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_b0d1ce-84 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_b0d1ce-84 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_b0d1ce-84 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_b0d1ce-84 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_b0d1ce-84{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_b0d1ce-84 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_b0d1ce-84 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_b0d1ce-84\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_d1850b-98, .wp-block-kadence-advancedheading.kt-adv-heading1399_d1850b-98[data-kb-block=\"kb-adv-heading1399_d1850b-98\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading1399_d1850b-98 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_d1850b-98[data-kb-block=\"kb-adv-heading1399_d1850b-98\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_d1850b-98 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_d1850b-98\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/load-weighing-measuring\/\" data-type=\"design-options\" data-id=\"1269\" rel=\"nofollow\">Measuring<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_e6d752-60 > .kt-inside-inner-col,.kadence-column1399_e6d752-60 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_e6d752-60 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_e6d752-60 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_e6d752-60 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_e6d752-60 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_e6d752-60{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_e6d752-60 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_e6d752-60 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_e6d752-60\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_0ce192-cb, .wp-block-kadence-advancedheading.kt-adv-heading1399_0ce192-cb[data-kb-block=\"kb-adv-heading1399_0ce192-cb\"]{display:block;margin-top:0px;text-align:left;font-size:1.1rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_0ce192-cb mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_0ce192-cb[data-kb-block=\"kb-adv-heading1399_0ce192-cb\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_0ce192-cb wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_0ce192-cb\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/materials-surfaces-coatings\/\" data-type=\"design-options\" data-id=\"1267\" rel=\"nofollow\">Materials &amp; Surfaces<\/a><\/span><\/div><\/div>\n\n<style>.kadence-column1399_9e9320-c9 > .kt-inside-inner-col,.kadence-column1399_9e9320-c9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1399_9e9320-c9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1399_9e9320-c9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1399_9e9320-c9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1399_9e9320-c9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1399_9e9320-c9{position:relative;}@media all and (max-width: 1024px){.kadence-column1399_9e9320-c9 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1399_9e9320-c9 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1399_9e9320-c9\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1399_c59851-61, .wp-block-kadence-advancedheading.kt-adv-heading1399_c59851-61[data-kb-block=\"kb-adv-heading1399_c59851-61\"]{display:block;margin-top:0px;text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1399_c59851-61 mark, .wp-block-kadence-advancedheading.kt-adv-heading1399_c59851-61[data-kb-block=\"kb-adv-heading1399_c59851-61\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading1399_c59851-61 wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading1399_c59851-61\"><a href=\"https:\/\/www.gradinlifts.com\/design-options\/gates-enclosures-guard-rails\/\" data-type=\"design-options\" data-id=\"1268\" rel=\"nofollow\">Gates &amp; Enclosures <\/a><\/span><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-3 kt-inner-tab_06a514-08\"><div class=\"kt-tab-inner-content-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4462_f39715-e4, .wp-block-kadence-advancedheading.kt-adv-heading4462_f39715-e4[data-kb-block=\"kb-adv-heading4462_f39715-e4\"]{display:block;margin-top:var(--global-kb-spacing-sm, 1.5rem);font-size:1.5rem;font-style:normal;color:#949aa3;}.wp-block-kadence-advancedheading.kt-adv-heading4462_f39715-e4 mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_f39715-e4[data-kb-block=\"kb-adv-heading4462_f39715-e4\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading4462_f39715-e4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_f39715-e4\"><strong>Stationary Scissor Dock Lift<\/strong><div class=\"elementor-element elementor-element-13bdd58 elementor-widget elementor-widget-text-editor\" data-id=\"13bdd58\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\" style=\"box-sizing: border-box; --flex-direction: initial; --flex-wrap: initial; --justify-content: initial; --align-items: initial; --align-content: initial; --gap: initial; --flex-basis: initial; --flex-grow: initial; --flex-shrink: initial; --order: initial; --align-self: initial; flex-basis: var(--flex-basis); flex-grow: var(--flex-grow); flex-shrink: var(--flex-shrink); order: var(--order); align-self: var(--align-self); flex-direction: var(--flex-direction); flex-wrap: var(--flex-wrap); justify-content: var(--justify-content); align-items: var(--align-items); align-content: var(--align-content); gap: var(--gap); position: relative; --swiper-theme-color: #000; --swiper-navigation-size: 44px; --swiper-pagination-bullet-size: 6px; --swiper-pagination-bullet-horizontal-gap: 6px; --widgets-spacing: 10px 10px; color: rgb(85, 85, 85); font-family: Roboto, sans-serif; transition: 0.3s linear; width: 610px; margin-block-end: 10px; margin-bottom: 0px; text-align: justify; font-size: 18px; line-height: 30px; white-space-collapse: collapse; background-color: rgb(255, 255, 255);\"><div class=\"elementor-widget-container\" style=\"box-sizing: border-box; transition: background .3s,border .3s,border-radius .3s,box-shadow .3s,transform var(--e-transform-transition-duration,.4s);\"><\/div><div class=\"elementor-widget-container\" style=\"box-sizing: border-box; transition: background .3s,border .3s,border-radius .3s,box-shadow .3s,transform var(--e-transform-transition-duration,.4s);\"><\/div><div class=\"elementor-widget-container\" style=\"box-sizing: border-box; transition: background .3s,border .3s,border-radius .3s,box-shadow .3s,transform var(--e-transform-transition-duration,.4s);\"><\/div><\/div><\/span>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4462_c6a64a-0d, .wp-block-kadence-advancedheading.kt-adv-heading4462_c6a64a-0d[data-kb-block=\"kb-adv-heading4462_c6a64a-0d\"]{padding-bottom:0px;margin-top:var(--global-kb-spacing-xs, 1rem);font-size:4rem;line-height:1;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading4462_c6a64a-0d mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_c6a64a-0d[data-kb-block=\"kb-adv-heading4462_c6a64a-0d\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading4462_c6a64a-0d wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_c6a64a-0d\">Structure &amp; Features<\/h2>\n\n<style>.kb-row-layout-id4462_a3a3ba-0b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4462_a3a3ba-0b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4462_a3a3ba-0b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id4462_a3a3ba-0b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4462_a3a3ba-0b > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4462_a3a3ba-0b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4462_a3a3ba-0b alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4462_6d103c-c4 > .kt-inside-inner-col,.kadence-column4462_6d103c-c4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_6d103c-c4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_6d103c-c4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_6d103c-c4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_6d103c-c4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_6d103c-c4{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_6d103c-c4 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_6d103c-c4 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_6d103c-c4 product-features\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4462_a038df-b4, .wp-block-kadence-advancedheading.kt-adv-heading4462_a038df-b4[data-kb-block=\"kb-adv-heading4462_a038df-b4\"]{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);font-size:1.3rem;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading4462_a038df-b4 mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_a038df-b4[data-kb-block=\"kb-adv-heading4462_a038df-b4\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading4462_a038df-b4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_a038df-b4\"><strong>Portable Design<\/strong><\/h3>\n\n<p>Easily movable to different locations for versatile loading and unloading operations.<\/p><\/div><\/div>\n\n<style>.kadence-column4462_05471d-ea > .kt-inside-inner-col,.kadence-column4462_05471d-ea > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_05471d-ea > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_05471d-ea > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_05471d-ea > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_05471d-ea > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_05471d-ea{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_05471d-ea > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_05471d-ea > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_05471d-ea product-features\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4462_07f949-f3, .wp-block-kadence-advancedheading.kt-adv-heading4462_07f949-f3[data-kb-block=\"kb-adv-heading4462_07f949-f3\"]{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);font-size:1.3rem;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading4462_07f949-f3 mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_07f949-f3[data-kb-block=\"kb-adv-heading4462_07f949-f3\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading4462_07f949-f3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_07f949-f3\"><strong>Scissor Mechanism<\/strong><\/h3>\n\n<p>Utilizes a robust scissor mechanism for smooth and efficient vertical lifting.<\/p><\/div><\/div>\n\n<style>.kadence-column4462_df2955-a7 > .kt-inside-inner-col,.kadence-column4462_df2955-a7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_df2955-a7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_df2955-a7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_df2955-a7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_df2955-a7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_df2955-a7{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_df2955-a7 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_df2955-a7 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_df2955-a7 product-features\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4462_af2a43-01, .wp-block-kadence-advancedheading.kt-adv-heading4462_af2a43-01[data-kb-block=\"kb-adv-heading4462_af2a43-01\"]{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);font-size:1.3rem;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading4462_af2a43-01 mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_af2a43-01[data-kb-block=\"kb-adv-heading4462_af2a43-01\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading4462_af2a43-01 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_af2a43-01\"><strong>Hydraulic Power<\/strong><\/h3>\n\n<p>Powered by a hydraulic system for precise control and stability during lifting.<\/p><\/div><\/div>\n\n<style>.kadence-column4462_57858b-6a > .kt-inside-inner-col,.kadence-column4462_57858b-6a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_57858b-6a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_57858b-6a > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_57858b-6a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_57858b-6a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_57858b-6a{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_57858b-6a > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_57858b-6a > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_57858b-6a product-features\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4462_71e1be-e0, .wp-block-kadence-advancedheading.kt-adv-heading4462_71e1be-e0[data-kb-block=\"kb-adv-heading4462_71e1be-e0\"]{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);font-size:1.3rem;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading4462_71e1be-e0 mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_71e1be-e0[data-kb-block=\"kb-adv-heading4462_71e1be-e0\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading4462_71e1be-e0 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_71e1be-e0\"><strong>Adjustable Height<\/strong><\/h3>\n\n<p>Adjustable platform height to accommodate various loading dock heights and truck bed levels.<\/p><\/div><\/div>\n\n<style>.kadence-column4462_1fd368-75 > .kt-inside-inner-col,.kadence-column4462_1fd368-75 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_1fd368-75 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_1fd368-75 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_1fd368-75 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_1fd368-75 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_1fd368-75{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_1fd368-75 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_1fd368-75 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_1fd368-75 product-features\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4462_3cf3b4-b3, .wp-block-kadence-advancedheading.kt-adv-heading4462_3cf3b4-b3[data-kb-block=\"kb-adv-heading4462_3cf3b4-b3\"]{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);font-size:1.3rem;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading4462_3cf3b4-b3 mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_3cf3b4-b3[data-kb-block=\"kb-adv-heading4462_3cf3b4-b3\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading4462_3cf3b4-b3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_3cf3b4-b3\"><strong>Safety Features<\/strong><\/h3>\n\n<p>Equipped with safety measures such as non-slip surfaces and guardrails to ensure safe operation.<\/p><\/div><\/div>\n\n<style>.kadence-column4462_0d8066-b6 > .kt-inside-inner-col,.kadence-column4462_0d8066-b6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_0d8066-b6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_0d8066-b6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_0d8066-b6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_0d8066-b6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_0d8066-b6{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_0d8066-b6 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_0d8066-b6 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_0d8066-b6 product-features\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4462_10d062-cf, .wp-block-kadence-advancedheading.kt-adv-heading4462_10d062-cf[data-kb-block=\"kb-adv-heading4462_10d062-cf\"]{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);font-size:1.3rem;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading4462_10d062-cf mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_10d062-cf[data-kb-block=\"kb-adv-heading4462_10d062-cf\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading4462_10d062-cf wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_10d062-cf\"><strong>Durable Construction<\/strong><\/h3>\n\n<p>Built with sturdy materials to withstand heavy loads and frequent use in industrial environments.<\/p><\/div><\/div>\n\n<style>.kadence-column4462_c894cf-7e > .kt-inside-inner-col,.kadence-column4462_c894cf-7e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_c894cf-7e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_c894cf-7e > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_c894cf-7e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_c894cf-7e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_c894cf-7e{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_c894cf-7e > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_c894cf-7e > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_c894cf-7e product-features\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4462_cb1519-cc, .wp-block-kadence-advancedheading.kt-adv-heading4462_cb1519-cc[data-kb-block=\"kb-adv-heading4462_cb1519-cc\"]{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);font-size:1.3rem;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading4462_cb1519-cc mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_cb1519-cc[data-kb-block=\"kb-adv-heading4462_cb1519-cc\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading4462_cb1519-cc wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_cb1519-cc\"><strong>Easy Operation<\/strong><\/h3>\n\n<p>Simple controls and user-friendly design make it easy to operate for efficient loading and unloading.<\/p><\/div><\/div>\n\n<style>.kadence-column4462_1fdb32-63 > .kt-inside-inner-col,.kadence-column4462_1fdb32-63 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_1fdb32-63 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_1fdb32-63 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_1fdb32-63 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_1fdb32-63 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_1fdb32-63{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_1fdb32-63 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_1fdb32-63 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_1fdb32-63 product-features\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4462_86ee2e-50, .wp-block-kadence-advancedheading.kt-adv-heading4462_86ee2e-50[data-kb-block=\"kb-adv-heading4462_86ee2e-50\"]{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);font-size:1.3rem;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading4462_86ee2e-50 mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_86ee2e-50[data-kb-block=\"kb-adv-heading4462_86ee2e-50\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading4462_86ee2e-50 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_86ee2e-50\"><strong>Versatile Applications<\/strong><\/h3>\n\n<p>Suitable for a wide range of loading dock and material handling applications, enhancing productivity and workflow efficiency.<\/p><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-4 kt-inner-tab_7ae1a0-7e\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id4462_88e4d6-05 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4462_88e4d6-05 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4462_88e4d6-05 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4462_88e4d6-05 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4462_88e4d6-05 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4462_88e4d6-05 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4462_88e4d6-05 alignnone cases-list-title product-detail-title2 wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4462_0fc5fb-2e > .kt-inside-inner-col,.kadence-column4462_0fc5fb-2e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_0fc5fb-2e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_0fc5fb-2e > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_0fc5fb-2e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_0fc5fb-2e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_0fc5fb-2e{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_0fc5fb-2e > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_0fc5fb-2e > .kt-inside-inner-col{flex-direction:column;}}.kadence-column4462_0fc5fb-2e {ndisplay: inline-block;n}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_0fc5fb-2e\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4462_a18d52-f3, .wp-block-kadence-advancedheading.kt-adv-heading4462_a18d52-f3[data-kb-block=\"kb-adv-heading4462_a18d52-f3\"]{margin-top:2rem;font-size:2rem;line-height:1;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4462_a18d52-f3 mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_a18d52-f3[data-kb-block=\"kb-adv-heading4462_a18d52-f3\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4462_a18d52-f3, .wp-block-kadence-advancedheading.kt-adv-heading4462_a18d52-f3[data-kb-block=\"kb-adv-heading4462_a18d52-f3\"]{font-size:1.3rem;}}<\/style>\n<h2 class=\"kt-adv-heading4462_a18d52-f3 case-title2 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_a18d52-f3\">Related Videos<\/h2><\/div><\/div>\n<\/div><\/div>\n\n<style>.kb-row-layout-id4462_dbb143-18 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4462_dbb143-18 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4462_dbb143-18 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4462_dbb143-18 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4462_dbb143-18 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4462_dbb143-18 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4462_dbb143-18 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4462_f23eb5-32, .kt-inside-inner-col > .kadence-column4462_f23eb5-32:not(.specificity){margin-right:20%;}.kadence-column4462_f23eb5-32 > .kt-inside-inner-col,.kadence-column4462_f23eb5-32 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_f23eb5-32 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_f23eb5-32 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_f23eb5-32 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_f23eb5-32 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_f23eb5-32{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_f23eb5-32 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_f23eb5-32, .kt-inside-inner-col > .kadence-column4462_f23eb5-32:not(.specificity){margin-right:0%;}.kadence-column4462_f23eb5-32 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_f23eb5-32\"><div class=\"kt-inside-inner-col\"><style>.kt-post-loop4462_d50825-c0 .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop4462_d50825-c0 .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop4462_d50825-c0 .kt-blocks-post-grid-item{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;overflow:hidden;}.kt-post-loop4462_d50825-c0 .kt-blocks-post-grid-item header{padding-top:5px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop4462_d50825-c0 .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:24px;line-height:30px;}.kt-post-loop4462_d50825-c0 .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#777777;}.kt-post-loop4462_d50825-c0 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a{color:#777777;}.kt-post-loop4462_d50825-c0 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a:hover{color:#444444;}.kt-post-loop4462_d50825-c0 .entry-content{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop4462_d50825-c0 .kt-blocks-post-footer{color:#777777;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:12px;line-height:20px;}.kt-post-loop4462_d50825-c0 .entry-content:after{height:0px;}.kt-post-loop4462_d50825-c0 .kt-blocks-post-footer a{color:#777777;}.kt-post-loop4462_d50825-c0 .kt-blocks-post-footer a:hover{color:#444444;}.kt-post-loop4462_d50825-c0 .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kt-post-loop4462_d50825-c0 .kt-blocks-post-grid-item{border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;}}@media all and (max-width: 767px){.kt-post-loop4462_d50825-c0 .kt-blocks-post-grid-item{border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;}}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop4462_d50825-c0 kt-post-grid-layout-grid  videos-main\"><div class=\"kt-post-grid-layout-grid-wrap kt-post-grid-wrap\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"data-item-selector=\".kt-post-masonry-item\"><p>No posts<\/p><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n<\/div><\/div>\n\n<style>.kb-row-layout-id4462_c95534-fa > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4462_c95534-fa > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4462_c95534-fa > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4462_c95534-fa > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4462_c95534-fa > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4462_c95534-fa > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4462_c95534-fa alignnone cases-list-title product-detail-title2 wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4462_6523ee-28 > .kt-inside-inner-col,.kadence-column4462_6523ee-28 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_6523ee-28 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_6523ee-28 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_6523ee-28 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_6523ee-28 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_6523ee-28{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_6523ee-28 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_6523ee-28 > .kt-inside-inner-col{flex-direction:column;}}.kadence-column4462_6523ee-28 {ndisplay: inline-block;n}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_6523ee-28\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4462_78d25e-9a, .wp-block-kadence-advancedheading.kt-adv-heading4462_78d25e-9a[data-kb-block=\"kb-adv-heading4462_78d25e-9a\"]{margin-top:3rem;font-size:2rem;line-height:1;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4462_78d25e-9a mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_78d25e-9a[data-kb-block=\"kb-adv-heading4462_78d25e-9a\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4462_78d25e-9a, .wp-block-kadence-advancedheading.kt-adv-heading4462_78d25e-9a[data-kb-block=\"kb-adv-heading4462_78d25e-9a\"]{font-size:1.3rem;}}<\/style>\n<h2 class=\"kt-adv-heading4462_78d25e-9a case-title2 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_78d25e-9a\">Related Case Studies<\/h2><\/div><\/div>\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedgallery.kb-gallery-wrap-id-4462_52e36f-29{margin-right:20%;}.wp-block-kadence-advancedgallery .kb-gallery-type-masonry.kb-gallery-id-4462_52e36f-29{margin:-5px;}.kb-gallery-type-masonry.kb-gallery-id-4462_52e36f-29 .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-4462_52e36f-29 .kadence-blocks-gallery-item .kb-gal-image-radius{border-radius:0px 0px 0px 0px;;}@media all and (max-width: 767px){.wp-block-kadence-advancedgallery.kb-gallery-wrap-id-4462_52e36f-29{margin-right:0%;margin-bottom:2%;}}<\/style><div class=\"kb-gallery-wrap-id-4462_52e36f-29 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-masonry kb-masonry-init kb-gallery-id-4462_52e36f-29 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\" \"><div class=\"kb-gal-image-radius\" style=\"max-width:500px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:72%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Mobile-Scissor-Loading-Dock-Lift-2.webp\" width=\"500\" height=\"360\" alt=\"\" data-full-image=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Mobile-Scissor-Loading-Dock-Lift-2.webp\" data-light-image=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Mobile-Scissor-Loading-Dock-Lift-2.webp\" data-id=\"4121\" class=\"wp-image-4121\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Mobile-Scissor-Loading-Dock-Lift-2.webp 500w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Mobile-Scissor-Loading-Dock-Lift-2-300x216.webp 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\" \"><div class=\"kb-gal-image-radius\" style=\"max-width:500px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:72%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Mobile-Scissor-Loading-Dock-Lift-3.webp\" width=\"500\" height=\"360\" alt=\"\" data-full-image=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Mobile-Scissor-Loading-Dock-Lift-3.webp\" data-light-image=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Mobile-Scissor-Loading-Dock-Lift-3.webp\" data-id=\"4122\" class=\"wp-image-4122\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Mobile-Scissor-Loading-Dock-Lift-3.webp 500w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Mobile-Scissor-Loading-Dock-Lift-3-300x216.webp 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\" \"><div class=\"kb-gal-image-radius\" style=\"max-width:460px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:71%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Mobile-Scissor-Loading-Dock-Lift-4.webp\" width=\"460\" height=\"330\" alt=\"\" data-full-image=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Mobile-Scissor-Loading-Dock-Lift-4.webp\" data-light-image=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Mobile-Scissor-Loading-Dock-Lift-4.webp\" data-id=\"4123\" class=\"wp-image-4123\" srcset=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Mobile-Scissor-Loading-Dock-Lift-4.webp 460w, https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Mobile-Scissor-Loading-Dock-Lift-4-300x215.webp 300w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/><\/div><\/div><\/figure><\/div><\/li><\/ul><\/div><\/div><\/div>\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-5 kt-inner-tab_d55742-3d\"><div class=\"kt-tab-inner-content-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4462_b9c749-c8, .wp-block-kadence-advancedheading.kt-adv-heading4462_b9c749-c8[data-kb-block=\"kb-adv-heading4462_b9c749-c8\"]{display:block;margin-top:var(--global-kb-spacing-sm, 1.5rem);font-size:1.5rem;font-style:normal;color:#949aa3;}.wp-block-kadence-advancedheading.kt-adv-heading4462_b9c749-c8 mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_b9c749-c8[data-kb-block=\"kb-adv-heading4462_b9c749-c8\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading4462_b9c749-c8 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_b9c749-c8\"><strong>Stationary Scissor Dock Lift<\/strong><div class=\"elementor-element elementor-element-13bdd58 elementor-widget elementor-widget-text-editor\" data-id=\"13bdd58\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\" style=\"box-sizing: border-box; --flex-direction: initial; --flex-wrap: initial; --justify-content: initial; --align-items: initial; --align-content: initial; --gap: initial; --flex-basis: initial; --flex-grow: initial; --flex-shrink: initial; --order: initial; --align-self: initial; flex-basis: var(--flex-basis); flex-grow: var(--flex-grow); flex-shrink: var(--flex-shrink); order: var(--order); align-self: var(--align-self); flex-direction: var(--flex-direction); flex-wrap: var(--flex-wrap); justify-content: var(--justify-content); align-items: var(--align-items); align-content: var(--align-content); gap: var(--gap); position: relative; --swiper-theme-color: #000; --swiper-navigation-size: 44px; --swiper-pagination-bullet-size: 6px; --swiper-pagination-bullet-horizontal-gap: 6px; --widgets-spacing: 10px 10px; color: rgb(85, 85, 85); font-family: Roboto, sans-serif; transition: 0.3s linear; width: 610px; margin-block-end: 10px; margin-bottom: 0px; text-align: justify; font-size: 18px; line-height: 30px; white-space-collapse: collapse; background-color: rgb(255, 255, 255);\"><div class=\"elementor-widget-container\" style=\"box-sizing: border-box; transition: background .3s,border .3s,border-radius .3s,box-shadow .3s,transform var(--e-transform-transition-duration,.4s);\"><\/div><div class=\"elementor-widget-container\" style=\"box-sizing: border-box; transition: background .3s,border .3s,border-radius .3s,box-shadow .3s,transform var(--e-transform-transition-duration,.4s);\"><\/div><div class=\"elementor-widget-container\" style=\"box-sizing: border-box; transition: background .3s,border .3s,border-radius .3s,box-shadow .3s,transform var(--e-transform-transition-duration,.4s);\"><\/div><\/div><\/span>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4462_b7e96e-12, .wp-block-kadence-advancedheading.kt-adv-heading4462_b7e96e-12[data-kb-block=\"kb-adv-heading4462_b7e96e-12\"]{padding-bottom:0px;margin-top:1rem;margin-bottom:3rem;font-size:4rem;line-height:1;font-style:normal;color:#0f182d;}.wp-block-kadence-advancedheading.kt-adv-heading4462_b7e96e-12 mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_b7e96e-12[data-kb-block=\"kb-adv-heading4462_b7e96e-12\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4462_b7e96e-12, .wp-block-kadence-advancedheading.kt-adv-heading4462_b7e96e-12[data-kb-block=\"kb-adv-heading4462_b7e96e-12\"]{font-size:2.3rem;}}<\/style>\n<h2 class=\"kt-adv-heading4462_b7e96e-12 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_b7e96e-12\">Product Documents<\/h2>\n\n<style>.kb-row-layout-id4462_b211aa-fe > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4462_b211aa-fe > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4462_b211aa-fe > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id4462_b211aa-fe > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4462_b211aa-fe > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4462_b211aa-fe > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4462_b211aa-fe alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4462_0e036c-6a > .kt-inside-inner-col{padding-top:2rem;padding-right:2rem;padding-bottom:2rem;padding-left:2rem;}.kadence-column4462_0e036c-6a > .kt-inside-inner-col,.kadence-column4462_0e036c-6a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_0e036c-6a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_0e036c-6a > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_0e036c-6a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_0e036c-6a > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column4462_0e036c-6a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_0e036c-6a{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_0e036c-6a > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_0e036c-6a > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_0e036c-6a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4462_fafe45-8b, .wp-block-kadence-advancedheading.kt-adv-heading4462_fafe45-8b[data-kb-block=\"kb-adv-heading4462_fafe45-8b\"]{font-size:1.5rem;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4462_fafe45-8b mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_fafe45-8b[data-kb-block=\"kb-adv-heading4462_fafe45-8b\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading4462_fafe45-8b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_fafe45-8b\">Company<\/h3>\n\n<style>.kb-row-layout-id4462_513c96-12 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4462_513c96-12 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4462_513c96-12 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-sm, 1rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(10% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(90% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id4462_513c96-12 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4462_513c96-12 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4462_513c96-12 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4462_513c96-12 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4462_da40bf-b5 > .kt-inside-inner-col,.kadence-column4462_da40bf-b5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_da40bf-b5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_da40bf-b5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_da40bf-b5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_da40bf-b5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_da40bf-b5{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_da40bf-b5 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_da40bf-b5 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_da40bf-b5\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons4462_459649-3f .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons4462_459649-3f{justify-content:flex-end;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons4462_459649-3f alignnone\"><style>.kt-svg-item-4462_a6faa0-4f .kb-svg-icon-wrap{font-size:25px;margin-right:0.4rem;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-4462_a6faa0-4f\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_file-pdf\"><svg viewBox=\"0 0 384 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M181.9 256.1c-5-16-4.9-46.9-2-46.9 8.4 0 7.6 36.9 2 46.9zm-1.7 47.2c-7.7 20.2-17.3 43.3-28.4 62.7 18.3-7 39-17.2 62.9-21.9-12.7-9.6-24.9-23.4-34.5-40.8zM86.1 428.1c0 .8 13.2-5.4 34.9-40.2-6.7 6.3-29.1 24.5-34.9 40.2zM248 160h136v328c0 13.3-10.7 24-24 24H24c-13.3 0-24-10.7-24-24V24C0 10.7 10.7 0 24 0h200v136c0 13.2 10.8 24 24 24zm-8 171.8c-20-12.2-33.3-29-42.7-53.8 4.5-18.5 11.6-46.6 6.2-64.2-4.7-29.4-42.4-26.5-47.8-6.8-5 18.3-.4 44.1 8.1 77-11.6 27.6-28.7 64.6-40.8 85.8-.1 0-.1.1-.2.1-27.1 13.9-73.6 44.5-54.5 68 5.6 6.9 16 10 21.5 10 17.9 0 35.7-18 61.1-61.8 25.8-8.5 54.1-19.1 79-23.2 21.7 11.8 47.1 19.5 64 19.5 29.2 0 31.2-32 19.7-43.4-13.9-13.6-54.3-9.7-73.6-7.2zM377 105L279 7c-4.5-4.5-10.6-7-17-7h-6v128h128v-6.1c0-6.3-2.5-12.4-7-16.9zm-74.1 255.3c4.1-2.7-2.5-11.9-42.8-9 37.1 15.8 42.8 9 42.8 9z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div>\n\n<style>.kadence-column4462_1c931c-8e > .kt-inside-inner-col,.kadence-column4462_1c931c-8e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_1c931c-8e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_1c931c-8e > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_1c931c-8e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_1c931c-8e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_1c931c-8e{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_1c931c-8e > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_1c931c-8e > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_1c931c-8e\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4462_61892c-f7, .wp-block-kadence-advancedheading.kt-adv-heading4462_61892c-f7[data-kb-block=\"kb-adv-heading4462_61892c-f7\"]{font-size:1rem;line-height:1.8;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4462_61892c-f7 mark, .wp-block-kadence-advancedheading.kt-adv-heading4462_61892c-f7[data-kb-block=\"kb-adv-heading4462_61892c-f7\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading4462_61892c-f7 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4462_61892c-f7\"><a href=\"https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/07\/JINAN-QUENTIN-MACHINERY-CO.LTD_.pdf\">JINAN QUENTIN MACHINERY CO.,LTD<\/a><\/p><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n<style>.kadence-column4462_a5eb6c-f6 > .kt-inside-inner-col,.kadence-column4462_a5eb6c-f6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_a5eb6c-f6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_a5eb6c-f6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_a5eb6c-f6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_a5eb6c-f6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_a5eb6c-f6{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_a5eb6c-f6 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_a5eb6c-f6 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_a5eb6c-f6\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<style>.kadence-column4462_f48d3e-f2 > .kt-inside-inner-col,.kadence-column4462_f48d3e-f2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4462_f48d3e-f2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4462_f48d3e-f2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4462_f48d3e-f2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4462_f48d3e-f2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4462_f48d3e-f2{position:relative;}@media all and (max-width: 1024px){.kadence-column4462_f48d3e-f2 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column4462_f48d3e-f2 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4462_f48d3e-f2\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>The stationary scissor lift platform adopts a steel frame structure or a high-strength steel plate structure. The carrying capacity ranges from 0.1 lo 100 tons. The product size and equipment size can be customized according to different needs of users. The operation mode can be divided into up and down control and single control on the ground, as well as point up and down and multi-layer control. The hydraulic lifting olatform specially designed to meet various special requirements can provide users with the best solutions for Ihe special needs of the lifting platform under the special working conditions in the fastest time.<\/p>","protected":false},"featured_media":4463,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"product_category":[],"application_category":[],"product_cat":[99],"product_tag":[142,148,80,202,143],"class_list":{"0":"post-4462","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-dock-lifts","7":"product_tag-durability","8":"product_tag-easy-operation","9":"product_tag-hydraulic","10":"product_tag-scissor-lift-platform","11":"product_tag-versatility","12":"pa_lift-capacity-6-ton","14":"first","15":"instock","16":"shipping-taxable","17":"product-type-simple","18":"entry","19":"content-bg","20":"loop-entry"},"acf":[],"taxonomy_info":{"product_cat":[{"value":99,"label":"Dock Lifts"}],"product_tag":[{"value":142,"label":"Durability"},{"value":148,"label":"Easy Operation"},{"value":80,"label":"Hydraulic"},{"value":202,"label":"Scissor Lift Platform"},{"value":143,"label":"Versatility"}],"pa_lift-capacity":[{"value":57,"label":"&gt; 6 ton"}]},"featured_image_src_large":["https:\/\/www.gradinlifts.com\/wp-content\/uploads\/2024\/08\/Stationary-Scissor-Dock-Lift.webp",750,750,false],"author_info":[],"comment_info":0,"_links":{"self":[{"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/product\/4462"}],"collection":[{"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/comments?post=4462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/media\/4463"}],"wp:attachment":[{"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/media?parent=4462"}],"wp:term":[{"taxonomy":"product_category","embeddable":true,"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/product_category?post=4462"},{"taxonomy":"application_category","embeddable":true,"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/application_category?post=4462"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/product_cat?post=4462"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.gradinlifts.com\/ko\/wp-json\/wp\/v2\/product_tag?post=4462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}